{"id":28223,"date":"2013-12-06T05:44:16","date_gmt":"2013-12-06T04:44:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28223"},"modified":"2023-01-17T13:25:37","modified_gmt":"2023-01-17T12:25:37","slug":"11779-due-incidenti-sulla-statale-18-il-bilancio-di-e-un-morto-e-4-feriti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11779-due-incidenti-sulla-statale-18-il-bilancio-di-e-un-morto-e-4-feriti\/","title":{"rendered":"Due incidenti sulla Statale 18, il bilancio di \u00e8 un morto e 4 feriti"},"content":{"rendered":"<p>PAOLA (CS) &#8211; Un incidente mortale si \u00e8 verificato ieri sulla statale 18 nel territorio di Paola, sul tirreno cosentino.<\/p>\n<p>  <!--more-->  <\/p>\n<p>A perdere la vita un uomo di 65 anni, Antonio Maio di Fuscaldo. Sono stati due in realt\u00e0 gli incidenti avvenuti ieri sulla statale 18 con un bilancio complessivo di una vittima e quattro feriti. Il primo si \u00e8 verificato intorno alla 15, tra una Fiat Punto e una Mercedes che ha provocato il ferimento di una donna. Ma \u00e8 stato il secondo incidente quello pi\u00f9 grave. Uno scontro frontale, avvenuto in localit\u00e0 Centacque, che ha provocato la morte di Maio, che si trovava a bordo di un fuoristrada assieme alla moglie e ad una sua parente. Nell\u2019altra vettura, un Audi A4, un 23enne, D.P. di Fuscaldo anch\u2019egli rimasto ferito. Sul posto la polizia stradale di Paola che ha effettuato i rilievi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PAOLA (CS) &#8211; Un incidente mortale si \u00e8 verificato ieri sulla statale 18 nel territorio di Paola, sul tirreno cosentino.<\/p>\n","protected":false},"author":19,"featured_media":28224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-28223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28223"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28224"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}