{"id":282345,"date":"2026-02-01T14:30:31","date_gmt":"2026-02-01T13:30:31","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=282345"},"modified":"2026-02-01T17:30:47","modified_gmt":"2026-02-01T16:30:47","slug":"tajani-regioni-maltempo-imprese-associazioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/tajani-regioni-maltempo-imprese-associazioni\/","title":{"rendered":"Il ministro Tajani visita le regioni colpite dal maltempo: incontrer\u00e0 imprese e associazioni locali"},"content":{"rendered":"<p>CATANZARO &#8211; Domani, luned\u00ec 2 febbraio, il Ministro degli Esteri Antonio Tajani visiter\u00e0 le tre regioni italiane pi\u00f9 colpite dal maltempo: <strong>Calabria<\/strong>, Sicilia e Sardegna. La visita, resa nota dalla <a href=\"https:\/\/www.esteri.it\/it\/sala_stampa\/archivionotizie\/comunicati\/2026\/01\/misure-farnesina-in-campo-per-le-regioni-colpite-dal-maltempo-tajani-in-calabria-sicilia-e-sardegna\/\" rel=\"noopener\">Farnesina<\/a>, prevede <strong>incontri con i presidenti regionali, le imprese e le associazioni del mondo produttivo locale.<\/strong><\/p>\n<p>L\u2019obiettivo \u00e8 <strong>approfondire le esigenze dei territori colpiti<\/strong> dalle recenti calamit\u00e0 e presentare le misure di supporto alle imprese messe a disposizione dal Ministero degli Affari Esteri e dalle agenzie di sostegno all\u2019export.<\/p>\n<h3>Tajani in Calabria, Sicilia e Sardegna<\/h3>\n<p>All\u2019incontro parteciperanno anche i vertici di Agenzia ICE, Simest, Cassa Depositi e Prestiti e SACE, per illustrare strumenti finanziari e agevolazioni a sostegno delle attivit\u00e0 economiche dei territori danneggiati.<\/p>\n<p>L\u2019iniziativa rientra nel pi\u00f9 ampio impegno del Governo per garantire assistenza concreta alle imprese locali e sostenere la ripresa economica nelle zone colpite da eventi climatici estremi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La visita del Ministro degli Esteri \u00e8 in programma per domani. Tajani illustrer\u00e0 strumenti di supporto e sostegno all\u2019export<\/p>\n","protected":false},"author":42,"featured_media":282346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-282345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/282345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=282345"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/282345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/282346"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=282345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=282345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=282345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}