{"id":28257,"date":"2013-12-07T10:05:44","date_gmt":"2013-12-07T09:05:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28257"},"modified":"2023-01-17T13:25:39","modified_gmt":"2023-01-17T12:25:39","slug":"11796-anas-le-modifiche-alla-viabilita-sull-a3-da-lunedi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11796-anas-le-modifiche-alla-viabilita-sull-a3-da-lunedi\/","title":{"rendered":"Anas, le modifiche alla viabilit\u00e0 sull\u2019A3 da luned\u00ec"},"content":{"rendered":"<p>CATANZARO &#8211; Alcuni provvedimenti dell&#8217;Anas relativamente alle modifiche della circolazione sull&#8217;A3 Salerno Reggio Calabria.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L\u2019Anas comunica che dalle ore 7:00 di luned\u00ec 9 dicembre alle ore 16,30 del 14 dicembre 2013 e dalle ore 7:00 del 16 dicembre alle ore 16:30 del 21 dicembre 2013 sar\u00e0 istituito un restringimento di carreggiata sulla strada statale 280 \u201cDei Due Mari\u201d, dal km 26,440 al km 27,800, in direzione Lamezia Terme-Catanzaro. Il provvedimento si rende necessario per consentire i lavori di costruzione della corsia di accelerazione dello svincolo Martelletto Sarrottino, tra i comuni di Settingiano e Marcellinara in provincia di Catanzaro. All\u2019approssimarsi delle aree di cantiere, i veicoli dovranno procedere rispettando il limite di velocit\u00e0 di 40 km\/h e il divieto di sorpasso.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019Anas inoltre, informa che da mercoled\u00ec 11 dicembre a gioved\u00ec 19 dicembre 2013, nella fascia oraria compresa tra le 9:00 e le 16:00 saranno attivi restringimenti di carreggiata su tratti saltuari del Raccordo Autostradale di Reggio Calabria tra i km 0,000 e 5,512. Il provvedimento si rende necessario per consentire lavori di manutenzione ordinaria alle opere d&#8217;arte e idrauliche e la pulizia del piano viabile e delle aree di pertinenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Alcuni provvedimenti dell&#8217;Anas relativamente alle modifiche della circolazione sull&#8217;A3 Salerno Reggio Calabria.<\/p>\n","protected":false},"author":22,"featured_media":28258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-28257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28257"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28258"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}