{"id":282575,"date":"2026-02-01T12:15:21","date_gmt":"2026-02-01T11:15:21","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=282575"},"modified":"2026-02-01T17:30:42","modified_gmt":"2026-02-01T16:30:42","slug":"tantissima-neve-in-sila-turisti-camigliatello","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/tantissima-neve-in-sila-turisti-camigliatello\/","title":{"rendered":"Tantissima neve in Sila: boom di turisti. A Camigliatello apre la pista blu, a Lorica impianti chiusi oggi per il maltempo"},"content":{"rendered":"<p>COSENZA \u2013 Neve in Sila, tanta, per la felicit\u00e0 di turisti e operatori economici. Le <strong>abbondanti precipitazioni di questa notte<\/strong> e delle prime ore del mattina, hanno lasciato al suolo <strong>quasi 30 centimetri a Camigliatello e Lorica<\/strong>, <strong>oltre i 50 cm sui versanti orientali dell\u2019altopiano Silano<\/strong>, mentre sulle vette pi\u00f9 alte, anche per le <a href=\"https:\/\/quicosenza.it\/news\/torna-la-neve-in-sila-nevicata-camigliatello\/\" target=\"_blank\" rel=\"noopener\">precipitazioni dei giorni scorsi<\/a>, oltre i 1500 metri <strong>si sfiora il metro di altezza<\/strong>. Tantissime le persone che questa mattina si sono recate in Sila, prendendo d\u2019assalto i due principali centri turistici: <strong>Camigliatello e Lorica<\/strong> per una bellissima domenica sulla neve.<br \/>\n<iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=476&amp;href=https%3A%2F%2Fwww.facebook.com%2Freel%2F919042083972850%2F&amp;show_text=false&amp;width=267&amp;t=0\" width=\"267\" height=\"476\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h3>Neve in Sila: a Camigliatello aperta la pista blu. A Lorica impianti chiusi<\/h3>\n<p>Fiocchi bianchi ma anche qualche problema a causa del maltempo di questa notte. Le\u00a0 forti raffiche di vento e una <strong>vera e propria<a href=\"https:\/\/quicosenza.it\/news\/forte-neve-chiusa-ss-108-bis-stop-lorica\/\" target=\"_blank\" rel=\"noopener\"> bufera<\/a><\/strong> che ha interessato la localit\u00e0 di Lorica e in <strong>particolare la parte alta del comprensorio di Monte Botte Donato<\/strong>, ha provocato <strong>la caduta di alcuni alberi sulle linee elettriche ENEL<\/strong>. Per motivi di sicurezza, ha spiegato <a href=\"https:\/\/www.facebook.com\/profile.php?id=61555329455978\" target=\"_blank\" rel=\"noopener\">Ferrovie della Calabria<\/a>, <strong>gli impianti del Comprensorio Sciistico di Lorica rimarranno chiusi<\/strong> per l\u2019intera giornata odierna. Tecnici e operatori sono al lavoro per poter riaprire domani mattina.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-281577 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Pista-da-Sci-camigliatello.jpg\" alt=\"Pista da Sci camigliatello Sila\" width=\"546\" height=\"340\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Pista-da-Sci-camigliatello.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Pista-da-Sci-camigliatello-300x187.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Pista-da-Sci-camigliatello-768x478.jpg 768w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/><\/p>\n<p>A Camigliatello invece, sempre per <strong>le condizioni meteo avverse e la fortissima nevicata,<\/strong> non \u00e8 stato possibile al momento aprite totalmente le aree sciabili. Come riporta l\u2019Arsac in una nota \u201c<strong>sar\u00e0 fruibile per la giornata odierna, la sola pista blu<\/strong> con ultimo tratto canalizzato sulla pista rossa. Il nostro staff \u00e8 costantemente al lavoro per garantire la massima sicurezza e fornire aggiornamenti tempestivi. Vi invitiamo a prestare attenzione sulle aree sciabili aperte\u201d. Aperta e affollata<strong> la scuola sci<\/strong> con il campo Scuola Principianti, <strong>a valle dell&#8217;impianto del Tasso<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-162770 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/impianti-risalita-camigliatello.jpg\" alt=\"impianti\" width=\"580\" height=\"359\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/impianti-risalita-camigliatello.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/impianti-risalita-camigliatello-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/impianti-risalita-camigliatello-768x475.jpg 768w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Sila si veste di bianco e richiama migliaia di visitatori. A Camigliatello aperta la pista Blu, a Lorica per oggi impianti chiusi a causa del maltempo<\/p>\n","protected":false},"author":55,"featured_media":282576,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-282575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/282575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=282575"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/282575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/282576"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=282575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=282575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=282575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}