{"id":28263,"date":"2013-12-07T09:23:39","date_gmt":"2013-12-07T08:23:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28263"},"modified":"2023-01-17T13:25:39","modified_gmt":"2023-01-17T12:25:39","slug":"11799-calabrese-ferito-in-un-agguato-a-reggio-emilia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11799-calabrese-ferito-in-un-agguato-a-reggio-emilia\/","title":{"rendered":"Calabrese ferito in un agguato a Reggio Emilia"},"content":{"rendered":"<p>REGGIO EMILIA &#8211; I colpi di arma da fuoco lo hanno raggiunto alla mano e a un polpaccio mentre rientrava a casa, alle 4.30 di mattina.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L&#8217;agguato \u00e8 avvenuto in via Franklin a Reggio Emilia; l&#8217;uomo di origini calabresi, Roberto Turr\u00e0, \u00e8 stato raggiunto da alcuni colpi mentre era davanti al cancello della propria abitazione dove vive con la compagna e la figlia. Turr\u00e0, \u00e8 rimasto lievemente ferito dai alcuni colpi di arma da fuoco, che lo hanno raggiunto di striscio a una mano e a un polpaccio. Sarebbe stato lui stesso, due ore dopo l&#8217;accaduto, a recarsi in ospedale. Le sue condizioni non sono gravi: dopo essere stato medicato, \u00e8 stato dimesso con una prognosi di 20 giorni. L&#8217;uomo \u00e8 stato poi accompagnato in questura, dove \u00e8 stato sentito sull&#8217;agguato sul quale al momento gli inquirenti mantengono il massimo riserbo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO EMILIA &#8211; I colpi di arma da fuoco lo hanno raggiunto alla mano e a un polpaccio mentre rientrava a casa, alle 4.30 di mattina.<\/p>\n","protected":false},"author":22,"featured_media":28264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-28263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28263"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28264"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}