{"id":28289,"date":"2013-12-09T11:55:57","date_gmt":"2013-12-09T10:55:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28289"},"modified":"2023-01-17T13:25:40","modified_gmt":"2023-01-17T12:25:40","slug":"11813-l-asp-di-cosenza-presenta-un-esposto-sugli-odontoiatri-abusivi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11813-l-asp-di-cosenza-presenta-un-esposto-sugli-odontoiatri-abusivi\/","title":{"rendered":"Asp Cosenza, esposto contro l&#8217;esercizio abusivo per la radiodiagnostica"},"content":{"rendered":"<p>COSENZA &#8211; La direzione generale dell&#8217;Azienda Sanitaria provinciale di Cosenza ha inoltrato un esposto relativamente all&#8217;esercizio abusivo nel settore della radiodiagnostica da parte di alcuni studi odontoiatrici.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Nell&#8217;esposto, inviato alla magistratura, a tutte le Regioni e alle Aziende sanitarie locali nonch\u00e8 ai carabinieri e al Ministero della Salute, si segnala &#8220;una situazione di illegalit\u00e0 diffusa negli studi odontoiatrici&#8221;. Si legge inoltre che &#8220;il settore della radiodiagnostica \u00e8 oggi colpito da un fenomeno caratterizzato dall&#8217;esercizio abusivo della professione da parte di medici odontoiatri non specializzati in radiodiagnostica&#8221;. Nell&#8217;esposto si sottolinea che gli studi dentistici hanno in dotazione apparecchi radiologici che, per le loro caratteristiche, dovrebbero essere installati in maniera opportuna, secondo la legge, e usati da personale specializzato. Ma che questo non avverrebbe, con gravi rischi per le persone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La direzione generale dell&#8217;Azienda Sanitaria provinciale di Cosenza ha inoltrato un esposto relativamente all&#8217;esercizio abusivo nel settore della radiodiagnostica da parte di alcuni studi odontoiatrici.<\/p>\n","protected":false},"author":19,"featured_media":28290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-28289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28289"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28290"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}