{"id":283155,"date":"2026-02-06T14:33:47","date_gmt":"2026-02-06T13:33:47","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=283155"},"modified":"2026-02-06T15:08:17","modified_gmt":"2026-02-06T14:08:17","slug":"raffiche-di-vento-fino-a-100-km-h-alberi-caduti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/raffiche-di-vento-fino-a-100-km-h-alberi-caduti\/","title":{"rendered":"Raffiche di vento fino a 100 km\/h, alberi caduti anche a Cosenza e strade bloccate. Il maltempo non da tregua"},"content":{"rendered":"<p><strong>COSENZA<\/strong> \u2013 Il <strong>maltempo continua a colpire la Calabria<\/strong> con piogge, <strong>raffiche di vento che sfiorano i 100 km\/h <\/strong>(sulle vette della Sila toccati quasi 110 Km\/h), mareggiate e numerosi disagi alla viabilit\u00e0 per frane, smottamenti e allagamenti come accaduto nella zona di <a href=\"https:\/\/quicosenza.it\/news\/maltempo-altomonte-allagamenti-fiume-piena\/\" target=\"_blank\" rel=\"noopener\">Altomonte<\/a>. Per la giornata odierna \u00e8 attualmente in vigore un\u2019<strong>allerta meteo arancione<\/strong> sulle aree tirreniche delle province di <strong>Cosenza, Catanzaro e Vibo Valentia<\/strong>, dove diversi Comuni, compresa la citt\u00e0 di Cosenza, hanno disposto preventivamente la <strong>chiusura delle scuole e di alcune aree pubbliche<\/strong> a scopo precauzionale.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid0WLYu7kNJ3cbJ5HXiLBwaFbDAkRmJ1p5NDQN1oZ5DD33uBeLnxdjBgcZn5ECjKHpCl%26id%3D100057489998327&amp;show_text=true&amp;width=500\" width=\"500\" height=\"430\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h3>Scende a gialla l&#8217;allerta meteo sul Tirreno<\/h3>\n<p>Le precipitazioni pi\u00f9 intense stanno interessando in particolare la <strong>zona settentrionale e centro-orientale della regione<\/strong>, mentre la <strong>Protezione Civile regionale<\/strong>, guidata da <strong>Domenico Costarella<\/strong>, monitora costantemente l\u2019evolversi della situazione in stretto contatto con le amministrazioni locali. Nel frattempo per domani il nuovo bollettino meteo emesso dalla ProCiv prevede sulle stesse zone un&#8217;<a href=\"https:\/\/pc2.protezionecivilecalabria.it\/api\/alerts\/last-mau\/attachment\" target=\"_blank\" rel=\"noopener\">&#8216;allerta gialla<\/a> per il pomeriggio di oggi e la giornata di domani.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Raffiche di vento a 100 Km\/h: criticit\u00e0 nel cosentino<\/strong><\/h3>\n<p>Le <strong>maggiori criticit\u00e0<\/strong> si registrano lungo i <strong>versanti tirrenici<\/strong> e nelle <strong>aree interne della provincia di Cosenza<\/strong>, dove le <strong>violente raffiche di vento<\/strong> hanno causato la <strong>caduta di diversi alberi<\/strong>, creando seri problemi alla circolazione stradale e situazioni di potenziale pericolo.\u00a0A <strong>Cosenza<\/strong>, in <strong>viale della Repubblica<\/strong>, un albero \u00e8 crollato sulla sede stradale rendendo necessario l\u2019intervento immediato degli operai della <strong>Cooperativa \u201cI Due Fiumi\u201d<\/strong>, che hanno provveduto alla rimozione e alla messa in sicurezza dell\u2019area.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-283158 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Albero-Caudo3.jpg\" alt=\"Albero caduto Cerisano\" width=\"586\" height=\"413\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Albero-Caudo3.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Albero-Caudo3-300x212.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Albero-Caudo3-768x542.jpg 768w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/p>\n<h3><strong>Alberi caduti anche Cerisano e Figline Vegliaturo<\/strong><\/h3>\n<p>Un altro episodio si \u00e8 verificato a <strong>Cerisano<\/strong>, dove nella mattinata un <strong>grosso albero \u00e8 precipitato al suolo<\/strong> a causa delle forti raffiche. Il <strong>sindaco<\/strong> ha invitato la cittadinanza alla <strong>massima prudenza<\/strong>, raccomandando di evitare <strong>corsi d\u2019acqua, zone soggette a frane e aree a rischio allagamento<\/strong>.\u00a0Situazione critica anche lungo la <strong>strada che collega Figline Vegliaturo a Piano Lago<\/strong>, in prossimit\u00e0 dello <strong>svincolo per contrada Salinella<\/strong>, dove un albero caduto ha <strong>occupato la carreggiata<\/strong>, rendendo difficoltoso il transito dei veicoli. Sempre a Figline Vegliaturo interdetta la strada verso il cimitero per una frana.<\/p>\n<p>Le autorit\u00e0 regionali e locali continuano a seguire con attenzione l\u2019evolversi del maltempo. La <strong>Protezione Civile<\/strong> rinnova l\u2019invito ai cittadini a limitare gli spostamenti non necessari e a mantenere comportamenti prudenti, soprattutto nelle zone maggiormente esposte a <strong>frane, allagamenti e caduta di alberi<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-283161 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Frana-Castrolibero.jpg\" alt=\"Frana Castrolibero\" width=\"541\" height=\"362\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Frana-Castrolibero.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Frana-Castrolibero-300x201.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Frana-Castrolibero-768x514.jpg 768w\" sizes=\"auto, (max-width: 541px) 100vw, 541px\" \/><\/p>\n<h3>Movimento franoso a Castrolibero: chiusa una strada<\/h3>\n<p>A Castrolibero, invece, le avverse condizioni meteorologiche e le piogge degli ultimi giorni hanno provocato <strong>una frana con ostruzione parziale del canale di scolo delle acque piovane<\/strong>. il Sindaco ha emesso un&#8217;ordinanza disponendo l\u2019i<strong>nterdizione alla circolazione veicolare e pedonale nel tratto indicato di Via San Marco<\/strong> fino al ripristino delle necessarie condizioni di sicurezza, al fine di tutelare la pubblica incolumit\u00e0.<\/p>\n<h3>Paola: sotto osservazione la linea ferroviaria<\/h3>\n<p>A Paola, gi\u00e0 duramente danneggiata dalle scorsa mareggiate, le onde sono tornate a colpire il lungomare.<strong> Sotto osservazione la zona a nord del Comune tirrenico<\/strong> ed in particolare <strong>il tracciato della ferrovia<\/strong>. Il mare, dopo a<strong>ver divorato la strada \u00e8 quasi arrivato a interessare la linea ferrata<\/strong> con un&#8217;impressionante erosione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-283160 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Paola-Ferrovia.jpg\" alt=\"Paola Ferrovia mareggiata\" width=\"510\" height=\"312\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Paola-Ferrovia.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Paola-Ferrovia-300x184.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Paola-Ferrovia-768x470.jpg 768w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/p>\n<p>La situazione viene costantemente seguita dal Comune e dal responsabile del settore tecnico del Comune di Paola, Alessandra Di Benedetto: Questa mattina, dopo essere stati nuovamente contatti dagli uffici comunali<strong>, i tecnici di RFI hanno effettuato un nuovo sopralluogo<\/strong> per analizzare la situazione e provvedere ad interventi rapidi. Se l&#8217;infrastruttura dovesse danneggiarsi si rischierebbe<strong> il blocco completo della circolazione<\/strong> isolando, di fatto, Calabria e Sicilia dal resto d&#8217;Italia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Raffiche violentissime a quasi 100 Km\/h e piogge intense colpiscono il cosentino: alberi caduti, strade parzialmente bloccate e numerosi interventi<\/p>\n","protected":false},"author":55,"featured_media":283156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-283155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/283155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=283155"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/283155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/283156"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=283155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=283155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=283155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}