{"id":28335,"date":"2013-12-11T09:49:59","date_gmt":"2013-12-11T08:49:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28335"},"modified":"2023-01-17T13:25:44","modified_gmt":"2023-01-17T12:25:44","slug":"11836-protesta-lsu-lpu-presidi-a-roseto-capo-spulico-e-a-lamezia-terme","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11836-protesta-lsu-lpu-presidi-a-roseto-capo-spulico-e-a-lamezia-terme\/","title":{"rendered":"Protesta Lsu Lpu, bloccato lo svincolo di Cosenza Sud"},"content":{"rendered":"<p>ROSETO CAPO SPULICO (CS) &#8211; In piazza, a partire da oggi, migliaia di lavoratori, pensionati, precari e disoccupati.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Lo avevano preannunciato ieri, in un comunicato congiunto, i segretari generali della Calabria di Cgil, Michele Gravano, Cisl, Paolo Tramonti e Uil, Roberto Castagna. \u201cNon vengono affrontati i nodi strutturali a partire dalla mancata riduzione delle tasse a lavoratori, pensionati ed imprese &#8211; ha dichiarato quest\u2019ultimo \u2013 e la manifestazione \u00e8 finalizzata a chiedere soluzioni definitive sulla stabilizzazione degli Lsu\/Lpu\u201d. Le vicende della nostra regione sulle gravi difficolt\u00e0 a livello economico, sociale e produttivo e gli evidenti stati di disoccupazione e precariato, richiedono un intervento reale.<\/p>\n<p>&nbsp;<\/p>\n<p>Per quanto riguarda i <strong>presidi<\/strong> un gruppo di Lsu e Lpu, sta manifestando davanti allo svincolo autostradale di Cosenza Sud della A3 Salerno-Reggio Calabria. Stamattina era stato attuato un primo sit-in davanti alla sede della Rai. Poi i manifestanti hanno deciso di recarsi nei pressi dello svincolo.<\/p>\n<p>&nbsp;<\/p>\n<p>Traffico bloccato, da parte dei lavoratori che aderiscono alla mobilitazione, anche sulla statale 106 all\u2019altezza di Roseto Capo Spulico, nel cosentino. Si registrano rallentamenti ma non si segnalano particolari problemi. Alla protesta sono presenti anche diversi sindaci dell\u2019alto jonio cosentino.<\/p>\n<p>&nbsp;<\/p>\n<p>Un presidio \u00e8 stato attuato anche nei pressi dell\u2019aeroporto di Lamezia Terme da parte di un centinaio di lavoratori Lsu ed Lpu che protestano contro la mancata stabilizzazione. L&#8217;attivita&#8217; dello scalo comunque prosegue regolarmente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROSETO CAPO SPULICO (CS) &#8211; In piazza, a partire da oggi, migliaia di lavoratori, pensionati, precari e disoccupati.<\/p>\n","protected":false},"author":22,"featured_media":28336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-28335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28335"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28336"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}