{"id":283628,"date":"2026-02-13T08:00:27","date_gmt":"2026-02-13T07:00:27","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=283628"},"modified":"2026-02-13T12:14:20","modified_gmt":"2026-02-13T11:14:20","slug":"giornata-mondiale-cardiopatie-rende-convegno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/giornata-mondiale-cardiopatie-rende-convegno\/","title":{"rendered":"Cardiopatie, oggi si vive fino all\u2019et\u00e0 adulta: a Rende il convegno &#8220;Dove ti porta il cuore&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; In occasione della <a href=\"https:\/\/piccoligrandicuori.it\/giornata-mondiale-cardiopatie-congenite\/\" target=\"_blank\" rel=\"noopener\"><strong>Giornata Mondiale delle Cardiopatie<\/strong><\/a>, sabato 14 febbraio a Rende, presso l&#8217;Hotel San Francesco, si svolger\u00e0 il convegno medico-scientifico, promosso dalla dr.ssa Maria Lucente dal titolo <strong>\u201cDove porta il cuore: le cardiopatie congenite dalla gravidanza all\u2019et\u00e0 adulta\u201d.<\/strong><\/p>\n<p>Un importante momento di <strong>confronto multidisciplinare<\/strong> dedicato alla presa in carico globale dei pazienti affetti da <a href=\"https:\/\/quicosenza.it\/news\/open-day-allospedale-di-cosenza-per-sensibilizzare-sulle-cardiopatie-congenite\/\" target=\"_blank\" rel=\"noopener\">cardiopatie congenite<\/a> lungo tutto l\u2019arco della vita che\u00a0 riunir\u00e0 specialisti di diverse discipline \u2013<strong> ginecologi, neonatologi, pediatri, cardiologi, cardiochirurghi, anestesisti,\u00a0 infermieri e professionisti sanitari<\/strong> \u2013 con l\u2019obiettivo di promuovere una visione moderna e integrata della gestione clinica di queste patologie complesse, che oggi, grazie ai progressi della medicina, consentono una sopravvivenza e una qualit\u00e0 di vita sempre maggiori fino all\u2019et\u00e0 adulta.<\/p>\n<h3>Il convegno sulle cardiopatie: temi e apprfondimenti<\/h3>\n<p>Investire nella diagnosi precoce e nell\u2019accesso a cure specialistiche significa offrire alle famiglie non solo una <strong>risposta clinica<\/strong> ma anche un<strong> percorso di accompagnamento e sostegno,<\/strong> fondamentale per affrontare con consapevolezza e fiducia una condizione complessa ma sempre pi\u00f9 trattabile.<\/p>\n<p>Particolare attenzione sar\u00e0 dedicata ai <strong>modelli organizzativi per la presa in carico integrata del paziente<\/strong>, elemento centrale per garantire continuit\u00e0 assistenziale, appropriatezza delle cure e personalizzazione dei percorsi terapeutici e all\u2019 importanza di reti strutturate e multidisciplinari, capaci di accompagnare il paziente dalla diagnosi prenatale, alla nascita, all\u2019infanzia, fino all\u2019et\u00e0 adulta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-283631 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Cardiopatie-2.jpg\" alt=\"Cardiopatie \" width=\"500\" height=\"333\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Cardiopatie-2.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Cardiopatie-2-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Cardiopatie-2-768x511.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>\u00abLe cardiopatie congenite oggi non possono pi\u00f9 essere considerate esclusivamente patologie pediatriche \u2013 dichiara la dr.ssa Maria Lucente, promotrice e responsabile scientifica del simposio e responsabile dell\u2019Unit\u00e0 Operativa di Cardiologia Pediatrica Perinatale e delle Cardiopatie Congenite dell\u2019Ospedale Annunziata di Cosenza \u2013. Grazie alla <strong>diagnosi prenatale e alle pianificazione in epoca perinatale<\/strong> i progressi diagnostici e terapeutici, sempre pi\u00f9 bambini raggiungono l\u2019et\u00e0 adulta, rendendo indispensabile la costruzione di modelli organizzativi integrati e percorsi assistenziali strutturati. \u00c8 fondamentale garantire continuit\u00e0 di cura, integrazione tra ospedale e territorio e un approccio multidisciplinare che metta davvero il paziente e la sua famiglia al centro del percorso di cura\u00bb.<\/p>\n<h3>Spazio alle novit\u00e0 della medicina tra diagnosi e terapie<\/h3>\n<p>Le sessioni tematiche riservano ampio spazio alle<strong> novit\u00e0 della diagnostica perinatale,<\/strong> dell\u2019emodinamica interventistica, ai nuovi sviluppi della medicina, dalla diagnosi precoce alle terapie innovative, dalle tecnologie avanzate alle nuove strategie di follow-up, con l\u2019obiettivo di offrire una visione aggiornata e prospettica delle possibilit\u00e0 cliniche e organizzative oggi disponibili.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-283629\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/cardiopatie-congenite-cosenza.jpg\" alt=\"cardiopatie congenite cosenza\" width=\"593\" height=\"367\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/cardiopatie-congenite-cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/cardiopatie-congenite-cosenza-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/cardiopatie-congenite-cosenza-768x475.jpg 768w\" sizes=\"auto, (max-width: 593px) 100vw, 593px\" \/><\/p>\n<p>Il convegno porr\u00e0 inoltre l\u2019attenzione sulla <strong>gestione dei pazienti cardiopatici nell\u2019integrazione ospedale\u2013territorio<\/strong>, evidenziando il ruolo fondamentale della collaborazione tra strutture ospedaliere, medicina territoriale e servizi sociosanitari per costruire percorsi di cura continui, coordinati e centrati sulla persona.<\/p>\n<p>Un appuntamento di grande rilevanza scientifica e sociale, patrocinato dalle Societ\u00e0 Italiana di Neonatologia, Societ\u00e0 Italiana di Cardiologia Pediatrica e di Medicina Emergenza Urgenza Pediatrica, che rappresenta un passo importante verso un modello di sanit\u00e0 sempre pi\u00f9 integrato, multidisciplinare e orientato alla presa in carico globale del paziente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani, sabato 14 febbraio presso l&#8217;Hotel San Francesco, si svolger\u00e0 il convegno medico-scientifico, promosso dalla dr.ssa Maria Lucente che si concentrer\u00e0 sulle cardiopatie congenite dalla gravidanza all\u2019et\u00e0 adulta <\/p>\n","protected":false},"author":90,"featured_media":283630,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-283628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/283628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=283628"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/283628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/283630"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=283628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=283628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=283628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}