{"id":28407,"date":"2013-12-14T07:55:11","date_gmt":"2013-12-14T06:55:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28407"},"modified":"2023-01-17T13:25:47","modified_gmt":"2023-01-17T12:25:47","slug":"11875-agguato-nel-reggino-ferito-un-quarant-enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11875-agguato-nel-reggino-ferito-un-quarant-enne\/","title":{"rendered":"Agguato nel reggino, ferito un quarant&#8217;enne"},"content":{"rendered":"<p>GIOIA TAURO (RC) &#8211; Agguato di stampo mafioso in provincia di Reggio.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un uomo di 40 anni, Giuseppe Pisano, e&#8217; stato ferito gravemente ferito da diversi colpi d&#8217;arma da fuoco mentre si trovava sulla strada provinciale che collega Gioia Tauro a Rizziconi, nel Reggino.&nbsp;L&#8217;uomo \u00e8 scampato alla morte nonostante gli siano stati sparati una ventina di colpi. Pisano, ferito all&#8217;inguine, \u00e8 ricoverato nell&#8217;ospedale di Polistena e non sarebbe in pericolo di vita. Secondo le prime notizie era gi\u00e0 noto alle forze dell&#8217;ordine per piccoli fatti datati nel tempo e non risulterebbe avere legami con la criminalit\u00e0. Sul&nbsp;posto sono intervenuti gli uomini del commissariato PS di Gioia Tauro, che hanno avviato le indagini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GIOIA TAURO (RC) &#8211; Agguato di stampo mafioso in provincia di Reggio.<\/p>\n","protected":false},"author":22,"featured_media":28408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-28407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28407"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28408"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}