{"id":28413,"date":"2013-12-14T09:05:42","date_gmt":"2013-12-14T08:05:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28413"},"modified":"2023-01-17T13:25:48","modified_gmt":"2023-01-17T12:25:48","slug":"11878-attentato-al-sindaco-di-motta-s-lucia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11878-attentato-al-sindaco-di-motta-s-lucia\/","title":{"rendered":"Attentato al sindaco di Motta S.Lucia"},"content":{"rendered":"<p>Motta Santa Lucia (CZ), &#8211; Incendiata nella notte l&#8217;auto del sindaco di Motta Santa Lucia, Amedeo Colacino.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L&#8217;incendio e&#8217; avvenuto nel corso della <strong>notte<\/strong> e ha completamente distrutto l&#8217;automobile del <strong>sindaco<\/strong> del piccolo centro montano dell&#8217;hinterland <strong>lametino<\/strong>, nel catanzarese. Non e&#8217; la prima volta che il primo cittadino subisce un&#8217;<strong>intimidazione<\/strong> del genere. Gia&#8217; nel 2010 un&#8217;altra automobile di sua proprieta&#8217; era stata incendiata. Dopo l&#8217;intimidazione di questa notte, <strong>Colacino<\/strong> si e&#8217; sfogato su facebook, spiegando anche di essere tentato di gettare la spugna: &#8220;Questa notte, ennesimo incendio doloso ha distrutto il mio secondo fuoristrada. Il primo mi era stato bruciato a dicembre 2010. Mi chiedo ha un senso fare il sindaco in questa <strong>dannata terra<\/strong>, che amo alla follia, ma fino a quando. E&#8217; per fortuna che non sono in un paese di mafia, altrimenti avrebbero arso pure me? Noi sindaci siamo in prima linea per miseri 1000 euro al mese, a differenza dei nostri parlamentari . Sto valutando seriamente di buttare la spugna&#8230;. sindaco Colacino&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Motta Santa Lucia (CZ), &#8211; Incendiata nella notte l&#8217;auto del sindaco di Motta Santa Lucia, Amedeo Colacino.<\/p>\n","protected":false},"author":22,"featured_media":28414,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-28413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28413"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28414"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}