{"id":284212,"date":"2026-02-16T19:12:17","date_gmt":"2026-02-16T18:12:17","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=284212"},"modified":"2026-02-16T19:12:17","modified_gmt":"2026-02-16T18:12:17","slug":"alloggi-aterp-favoritismi-consigliere-costanzo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/alloggi-aterp-favoritismi-consigliere-costanzo\/","title":{"rendered":"Scandalo alloggi Aterp e favoritismi: sei anni chiesti per il consigliere Costanzo"},"content":{"rendered":"<p>CATANZARO &#8211; <a href=\"https:\/\/quicosenza.it\/news\/sistema-aterp-assegnazioni-illecite-di-alloggi-popolari-interdetti-due-vigili-urbani\/\" target=\"_blank\" rel=\"noopener\"><strong>Scandalo alloggi Aterp.<\/strong> <\/a>Il procuratore aggiunto di Catanzaro, Giulia Pantano, e il sostituto procuratore Saverio Sapia hanno invocato tre condanne e un&#8217;assoluzione nei confronti degli imputati nel processo con rito abbreviato nato dall&#8217;inchiesta sul presunto mercimonio degli alloggi gestiti dall\u2019<a href=\"https:\/\/www.aterpcalabria.it\/contatti\/\" target=\"_blank\" rel=\"noopener\"><strong>Azienda territoriale per l\u2019Edilizia Residenziale Pubblica Regionale <\/strong><\/a>di Catanzaro.<\/p>\n<p>L&#8217;accusa ha chiesto sei anni di reclusione nei confronti del<strong> consigliere comunale del capoluogo Sergio Costanzo<\/strong>; due anni per il <strong>funzionario dirigente dell&#8217;ufficio Patrimonio ed inquilinato<\/strong> <strong>Domenico Albino<\/strong>;<strong> 2 anni e 6 mesi per l&#8217;inquilina Aterp Teresa Mancuso e l&#8217;assoluzione per l&#8217;inquilino Saverio Mensica<\/strong>. Nel corso del processo \u00e8 intervenuta anche, quale parte civile, la difesa dell&#8217;Aterp che ha chiesto l&#8217;accoglimento della domanda di risarcimento per i danni subiti dall&#8217;Ente.<\/p>\n<h3>Sistema Aterp, Costanzo mediatore tra cittadini e dipendenti<\/h3>\n<p>Secondo l&#8217;accusa, nel &#8220;sistema Aterp&#8221;, <strong>Costanzo<\/strong> avrebbe avuto &#8220;funzione di<strong> raccordo tra cittadini che intendono aggirare o agevolare le proprie posizioni alloggiative ed i dipendenti dell&#8217;Aterp<\/strong> di Catanzaro&#8221;. Funzionari e dipendenti dell&#8217;ente avrebbero individuato alloggi liberi da allocare illecitamente, suggerendo di volta in volta modalit\u00e0 solo apparentemente legittime, quali la procedura cosiddetta di &#8220;ampliamento del nucleo familiare&#8221;, o di &#8220;cambio alloggio&#8221;, o tal volta addirittura proponendo l&#8217;occupazione di alloggi liberi per successivamente chiederne la regolarizzazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo l\u2019accusa, nel cosiddetto \u201csistema Aterp\u201d funzionari e politici avrebbero favorito l\u2019assegnazione illecita di alloggi popolari attraverso procedure fittizie come cambi o ampliamenti di nucleo familiare.<\/p>\n","protected":false},"author":58,"featured_media":248362,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-284212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/284212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=284212"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/284212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/248362"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=284212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=284212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=284212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}