{"id":285433,"date":"2026-03-01T16:40:49","date_gmt":"2026-03-01T15:40:49","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=285433"},"modified":"2026-03-01T16:41:52","modified_gmt":"2026-03-01T15:41:52","slug":"cosenza-vince-sorrento-partita-pazza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-vince-sorrento-partita-pazza\/","title":{"rendered":"Il Cosenza vince contro il Sorrento, ma che partita pazza: \u00e8 successo di tutto"},"content":{"rendered":"<p>COSENZA &#8211; Un successo al cardiopalma per il <strong>Cosenza<\/strong> che batte il <strong>Sorrento<\/strong> con non poche sofferenze. Tre rigori assegnati e doppio svantaggio da gestire per i calabresi. Busc\u00e8 sale a 50 punti in classifica, per i campani 33 punti e qualche punto di distacco dalla zona playout.<\/p>\n<p>Squalificato <strong>Cannav\u00f2 <a href=\"https:\/\/quicosenza.it\/news\/atalanta-u23-cosenza-calcio-0-0-noia\/\" target=\"_blank\" rel=\"noopener\">dopo la trasferta di Caravaggio<\/a><\/strong>, al suo posto arretra <strong>Ciotti<\/strong>: i calabresi si posizionano in campo con un 4-3-3. Per il <strong><a href=\"https:\/\/www.fcsorrento.com\" target=\"_blank\" rel=\"noopener\">Sorrento<\/a><\/strong> spazio invece al 4-3-1-2 e a caccia di punti per mantenersi lontana dalle zone basse della classifica.<\/p>\n<h2>Un rigore per parte: pari fra Cosenza e Sorrento<\/h2>\n<p>La prima occasione arriva al 4&#8242; con un tiro di <strong>D&#8217;Ursi<\/strong> terminato al lato rispetto alla porta difesa da <strong>Pompei<\/strong>. La risposta dei padroni di casa arriva dai piedi di <strong>Langella<\/strong> che tenta la giocata in seguito ad un calcio d&#8217;angolo: palla fuori. Dopo una fase iniziale maggiormente propositiva, da parte dei padroni di casa, cresce la manovra offensiva degli ospiti. Il Sorrento cerca di giocare sulle fasce, Cosenza guardingo e a caccia della giusta giocata.<\/p>\n<p>Al 18&#8242; tocco morbido di <strong>Sabbatani<\/strong>, su lancio di <strong>Capezzi<\/strong>, ma la palla non entra per una questione di pochi centimetri: prima vera occasione del match. Ma il Sorrento conquista un calcio di rigore per un fallo di Pompei su colpo ravvicinato ai danni di D&#8217;Ursi: sul dischetto va D&#8217;Ursi che non sbaglia e porta in vantaggio gli ospiti.<\/p>\n<div id=\"attachment_285437\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-285437\" class=\"wp-image-285437 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Cosenza-Sorrento.jpg\" alt=\"Cosenza Sorrento\" width=\"540\" height=\"334\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Cosenza-Sorrento.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Cosenza-Sorrento-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Cosenza-Sorrento-768x475.jpg 768w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><p id=\"caption-attachment-285437\" class=\"wp-caption-text\">Cosenza e Sorrento, i due episodi con conseguenti calci di rigore (foto Marco Belmonte)<\/p><\/div>\n<p>I Lupi non ci stanno e tentano la reazione di forza con <strong>Palmieri<\/strong> che, per\u00f2, non riesce a segnare con un tiro dalla distanza. L&#8217;arbitro viene richiamato dalla panchina dei campani per un fallo di <strong>Ciotti<\/strong>, ma dopo la revisione si resta fermi sulla decisione: solo ammonizione per il calciatore dei Lupi.<\/p>\n<p>Ma \u00e8 <strong>Dametto<\/strong> a tentare il gol della domenica da centrocampo: portiere avversario costretto ad intervenire in maniera tempestiva. Fallo di <strong>Paglino<\/strong> ai danni di Dametto e dopo una lunga revisione l&#8217;arbitro concede il rigore: dagli 11 metri segna <strong>Emmausso<\/strong>.<\/p>\n<h3>Quante polemiche, errore con gol del Sorrento e pari di Beretta<\/h3>\n<p>Erroraccio nella ripresa di Pompei e anche del difensore <strong>Moretti<\/strong> con conseguente gol di <strong>D&#8217;Ursi <\/strong>che approfitta dell&#8217;indecisione della retroguardia e realizza un gol dopo il lancio del compagno <strong>Colombini<\/strong>: l&#8217;arbitro va al monitor per verificare un eventuale tocco di mano. Ma i calabresi non mollano e con una giocata sull&#8217;asse <strong>Florenzi<\/strong>&#8211;<strong>Beretta<\/strong> si va sul 2-2.<\/p>\n<div id=\"attachment_285440\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-285440\" class=\"wp-image-285440 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Giacomo-Beretta.jpg\" alt=\"Beretta Cosenza \" width=\"540\" height=\"349\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Giacomo-Beretta.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Giacomo-Beretta-300x194.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Giacomo-Beretta-768x496.jpg 768w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><p id=\"caption-attachment-285440\" class=\"wp-caption-text\">Beretta poco prima di andare a segno (foto Belmonte)<\/p><\/div>\n<h3>Doppietta di Emmausso (ancora su rigore)<\/h3>\n<p>Al 61&#8242; Emmausso ha una buona occasione, il colpo di testa in torsione non trova per\u00f2 lo specchio della porta avversaria. Nel frattempo da un lato esce <strong>Garritano<\/strong> (al suo posto di <strong>Contiliano<\/strong>), dall&#8217;altro esce Paglino ed entra <strong>Fusco<\/strong>. Ma oggi c&#8217;\u00e8 un altro episodio a far discutere: rigore richiesto dai ragazzi allenati da Busc\u00e8 per un presunto tocco di Del Sorbo ai danni di Beretta.<\/p>\n<p>Dopo una lunga revisione \u00e8 il momento della <strong>decisione<\/strong> con l&#8217;arbitro che conferma il rigore. Dal dischetto si reca Emmausso che non sbaglia e realizza la doppietta di giornata.<\/p>\n<div id=\"attachment_285441\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-285441\" class=\"wp-image-285441 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Michele-Emmausso.jpg\" alt=\"Emmausso Cosenza \" width=\"540\" height=\"405\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Michele-Emmausso.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Michele-Emmausso-300x225.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Michele-Emmausso-768x576.jpg 768w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><p id=\"caption-attachment-285441\" class=\"wp-caption-text\">Emmausso segna il rigore del 3-2 (foto Belmonte)<\/p><\/div>\n<p>Al minuto 87 <strong>Portanova<\/strong> ha una chance enorme dinanzi al portiere, ma la conclusione del giocatore termina abbondantemente alta sopra la traversa. Il Sorrento ci prova con le energie residue, i silani per\u00f2 resistono e portano a casa un successo importantissimo e sofferto (complice l&#8217;ampio recupero concesso dall&#8217;arbitro).<\/p>\n<h3>Il tabellino di Cosenza-Sorrento<\/h3>\n<p><strong>COSENZA<\/strong> (4-3-3): Pompei; Ciotti, Moretti, Dametto, Caporale; Garritano (62&#8242; Contiliano), Langella, Palmieri; Florenzi (83&#8242; Ferrara), Beretta, Emmausso (91&#8242; Baez). In panchina: Vannucchi, Contiero, Pintus, Achour, Ba, Ferrara, Mazzulla. Allenatore: Busc\u00e8.<\/p>\n<p><strong>SORRENTO<\/strong> (4-3-1-2): Del Sorbo; Paglino (65&#8242; Fusco), Portanova, Solcia (89&#8242; Santini), Colombini; Cuccurello, Capezzi (82&#8242; Potenza), Cangianello (82&#8242; Crecco); Ricci (82&#8242; Esposito); D&#8217;Ursi, Sabbatani. In panchina: Harrasser, D&#8217;Aniello, Tonni, Bernabeo, Matera, Diop, Milan. \u00a0Allenatore: Serpini.<\/p>\n<p><strong>ARBITRO<\/strong>: Deborah Bianchi di Prato. <strong>Assistenti<\/strong>: Luca Capriuolo di Bari e Angelo Tomasi di Lecce. <strong>Quarto Ufficiale<\/strong>: Domenico Mirabella di Napoli. <strong>Operatore FVS<\/strong>: Luca Marucci di Rossano.<\/p>\n<p><strong>MARCATORI<\/strong>: 24&#8242; e 49&#8242; D&#8217;Ursi rig. (S), 45&#8217;+4&#8242; e 78&#8242; Emmausso rig. (C), 59&#8242; Beretta (C).<\/p>\n<p><strong>NOTE<\/strong>: spettatori 500 circa, una trentina gli ospiti. Espulso al 54&#8242; st il ds Roma (C). Espulso al 72&#8242; l&#8217;allenatore Busc\u00e8 (C) per proteste. Ammoniti: Ciotti, Langella (C), Paglino, Sabbatani, Del Sorbo (S). Angoli: 5-6. Recupero: 6&#8217;+4&#8242; pt, 8&#8242; st.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tre rigori assegnati durante la gara del &#8220;Marulla&#8221;, ma alla fine vince il Cosenza. Un match infinito a suon di penalty, polemiche, super recuperi e anche qualche espulsione<\/p>\n","protected":false},"author":93,"featured_media":285442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-285433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/285433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=285433"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/285433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/285442"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=285433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=285433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=285433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}