{"id":285595,"date":"2026-03-03T13:00:09","date_gmt":"2026-03-03T12:00:09","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=285595"},"modified":"2026-03-03T11:48:33","modified_gmt":"2026-03-03T10:48:33","slug":"sila3vette-2026-nel-cuore-parco-nazionale-sila","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sila3vette-2026-nel-cuore-parco-nazionale-sila\/","title":{"rendered":"Sila3Vette 2026: oltre 200 atleti nel cuore del Parco Nazionale della Sila"},"content":{"rendered":"<p>CAMIGLIATELLO SILANO &#8211; Nel cuore del <a href=\"https:\/\/quicosenza.it\/news\/il-parco-nazionale-della-sila-lancia-sportello\/\">Parco Nazionale della Sila<\/a> si \u00e8 svolta l\u2019edizione 2026 di<strong> <a href=\"https:\/\/www.sila3vette.com\/\" rel=\"noopener\">Sila3Vette<\/a><\/strong>. Un traguardo impensabile per gli organizzatori, che oggi posiziona questa <strong>winter challenge<\/strong>, la pi\u00f9 a sud d\u2019Europa, tra le <strong>regine delle competizioni invernali.<\/strong><\/p>\n<p>Dai 54 atleti della prima edizione, si \u00e8 passati agli oltre 200 partecipanti di quest\u2019anno, molti dei quali possono vantare un palmar\u00e8s di tutto rispetto nelle rispettive specialit\u00e0. L\u2019edizione 2026 ha inoltre registrato la partecipazione dell\u2019atleta canadese residente in Svizzera, <strong>Mathieu Plamondon<\/strong>, gi\u00e0 noto nel panorama delle ultra italiane: a gennaio si \u00e8 classificato sesto alla La Grande Corsa Bianca.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-285597 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Mathieu-Plamondon.jpg\" alt=\"Sila3Vette 2026: oltre 200 atleti nel cuore del Parco Nazionale della Sila\" width=\"418\" height=\"205\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Mathieu-Plamondon.jpg 1528w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Mathieu-Plamondon-300x147.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Mathieu-Plamondon-1024x503.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/Mathieu-Plamondon-768x377.jpg 768w\" sizes=\"auto, (max-width: 418px) 100vw, 418px\" \/><\/p>\n<h3>Sila3Vette. Un&#8217;idea di Pippo Guzzo e Mara Carchidi<\/h3>\n<p>Quando \u00e8 nata l\u2019avventura di Sila3Vette, gli ideatori, P<strong>ippo Guzzo e Mara Carchidi,<\/strong> non sapevano neanche come gestirla inizialmente. Ma nel 2016 erano certi di una cosa: l\u2019Altopiano Silano era un territorio importante. Un territorio fuori dalle rotte commerciali, che meritava di essere vissuto e raccontato. Cos\u00ec come meritavano di essere valorizzati gli uomini e le storie vere, i luoghi che, anche nella loro povert\u00e0 o nelle loro difficolt\u00e0, custodiscono una storia che va ascoltata.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-285598 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/pippo-e-mara.jpg\" alt=\"Sila3Vette 2026: oltre 200 atleti nel cuore del Parco Nazionale della Sila\" width=\"495\" height=\"280\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/pippo-e-mara.jpg 1468w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/pippo-e-mara-300x170.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/pippo-e-mara-1024x580.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/pippo-e-mara-768x435.jpg 768w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/p>\n<h3>Sila3Vette. Grande presenza sulla 40 km entry level di questa edizione<\/h3>\n<p>Quest\u2019anno poi grande presenza sulla 40 km la entry level di questa edizione che ha accolto sia i neofiti di questa specialit\u00e0 sia gli appassionati di <strong>trail running.<\/strong> In Sila3Vette molti trovano un momento di sfogo e di libert\u00e0, perch\u00e9 ormai questo appuntamento non \u00e8 solo una sfida sportiva, ma anche un\u2019<strong>esperienza emozionante<\/strong>: un vero e proprio viaggio introspettivo. Le condizioni meteo sono state perfette e, durante la notte, diversi atleti hanno tolto il frontale per godere di scenari meravigliosi e del riflesso delle stelle sulla neve. Come ogni anno, inoltre, si \u00e8 svolta anche la 9 km dedicata agli esordienti, per permettere anche a chi \u00e8 alla prima esperienza di sentirsi parte di questa grande avventura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019edizione 2026 di Sila3Vette conferma la crescita della winter challenge pi\u00f9 a sud d\u2019Europa: da 54 a oltre 200 atleti, con la partecipazione internazionale di Mathieu Plamondon<\/p>\n","protected":false},"author":66,"featured_media":285596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-285595","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-provincia","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/285595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=285595"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/285595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/285596"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=285595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=285595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=285595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}