{"id":285847,"date":"2026-03-05T09:37:56","date_gmt":"2026-03-05T08:37:56","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=285847"},"modified":"2026-03-05T13:06:23","modified_gmt":"2026-03-05T12:06:23","slug":"sequestrano-uomo-vincita-slot-pesciolino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sequestrano-uomo-vincita-slot-pesciolino\/","title":{"rendered":"Sequestrano e rapinano un uomo per la vincita alle slot con il metodo del &#8220;pesciolino&#8221;: 6 arresti"},"content":{"rendered":"<p>CIRO&#8217; MARINA (KR) &#8211; Al centro della vicenda c\u2019\u00e8 la cosiddetta tecnica del \u201c<strong>pesciolino<\/strong>\u201d, un arnese metallico che consentirebbe di giocare alle slot machine senza inserire monete, permettendo quindi di ottenere vincite ritenute irregolari. Sei persone sono state arrestate a Cir\u00f2 Marina con l\u2019accusa di <strong>sequestro di persona<\/strong> a scopo di <strong>estorsione<\/strong> e <strong>rapina<\/strong> in concorso. L\u2019operazione \u00e8 stata condotta dai Carabinieri della Compagnia di Cir\u00f2 Marina, con il supporto delle Compagnie di Crotone e Petilia Policastro e del Nucleo Carabinieri Cinofili di Vibo Valentia.<\/p>\n<h3>Il metodo del &#8220;pesciolino&#8221; e il sequestro di persona<\/h3>\n<p>Il provvedimento cautelare \u00e8 stato emesso dal Gip di Catanzaro su richiesta della Direzione Distrettuale Antimafia. Secondo gli investigatori, nei confronti degli indagati emergono gravi indizi di colpevolezza per i reati contestati.\u00a0Le indagini sono state condotte <strong>tra febbraio e<\/strong> <strong>maggio 2025<\/strong> e hanno riguardato un <strong>episodio avvenuto il 29 gennaio dello stesso anno a Cir\u00f2 Marina.<\/strong><\/p>\n<p>La vittima \u00e8 un <strong>uomo di origini campane<\/strong> che, secondo quanto ricostruito dagli investigatori, <strong>era stato preso di mira dal gruppo dopo alcune vincite ottenute alle slot machine tra Cariati e Cir\u00f2 Marina. <\/strong>Gli indagati <strong>sospettavano<\/strong> che l\u2019uomo avesse utilizzato un sistema illecito per vincere. Ritenendo che l\u2019uomo avesse utilizzato questo metodo, i 6 avrebbero deciso di intervenire per ottenere denaro in cambio della sua liberazione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-285849\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/pesciolino-slot-carabinieri-ciro.jpg\" alt=\"pesciolino slot carabinieri cir\u00f2\" width=\"658\" height=\"407\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/pesciolino-slot-carabinieri-ciro.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/pesciolino-slot-carabinieri-ciro-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/pesciolino-slot-carabinieri-ciro-768x475.jpg 768w\" sizes=\"auto, (max-width: 658px) 100vw, 658px\" \/><\/p>\n<h3>Aggressione e sequestro nel piazzale di un bar<\/h3>\n<p>Secondo la ricostruzione degli investigatori, la<strong> vittima sarebbe stata bloccata nel piazzale antistante un bar<\/strong> situato <strong>sulla statale 106<\/strong>, nel territorio di Cir\u00f2 Marina. Poi sarebbe stata aggredita, percossa e successivamente costretta a entrare nel bagno dell\u2019esercizio commerciale, dove gli indagati avrebbero <strong>preteso<\/strong> il <strong>pagamento di 5 mila euro<\/strong> come prezzo per riottenere la libert\u00e0. Durante l\u2019azione, gli indagati \u2013 ognuno con un ruolo specifico \u2013 avrebbero agito con <strong>violenza e con continue minacce di morte.<\/strong><\/p>\n<p>Secondo quanto emerso dalle indagini, il gruppo si sarebbe <strong>impossessato del portafogli della vittima contenente 620 euro<\/strong>, <strong>della sua autovettura e di ulteriori 1.800 euro.<\/strong><\/p>\n<h3>Il trucco del &#8220;pesciolino&#8221; nelle slot machine<\/h3>\n<p>Il cosiddetto trucco del \u201cpesciolino\u201d \u00e8 uno dei metodi pi\u00f9 noti utilizzati per tentare di truffare le slot machine. Il nome deriva dalla forma dell\u2019oggetto utilizzato: un <strong>piccolo dischetto metallico simile a una moneta<\/strong>, collegato a<strong> un filo o a un sottile cavo metallico, che ricorda appunto un pesce agganciato all\u2019amo.<\/strong> Il dischetto viene inserito nella fessura della slot machine destinata alle monete per simulare il pagamento della giocata. In realt\u00e0 l\u2019oggetto non viene mai lasciato all\u2019interno della macchina: grazie al filo metallico, infatti, pu\u00f2 essere recuperato rapidamente subito dopo l\u2019inserimento. <strong>L\u2019obiettivo \u00e8 far credere al dispositivo che sia stata inserita una moneta<\/strong>, ottenendo cos\u00ec gli spin di gioco senza spendere denaro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vittima aggredita e minacciata per aver utilizzato il cosiddetto metodo del \u201cpesciolino\u201d. Le indagini dopo i fatti del gennaio 2025<\/p>\n","protected":false},"author":42,"featured_media":285848,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-285847","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/285847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=285847"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/285847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/285848"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=285847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=285847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=285847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}