{"id":285850,"date":"2026-03-15T09:00:26","date_gmt":"2026-03-15T08:00:26","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=285850"},"modified":"2026-03-12T16:57:32","modified_gmt":"2026-03-12T15:57:32","slug":"allarme-tumori-2025-stimati-362mila-nord-sud","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/allarme-tumori-2025-stimati-362mila-nord-sud\/","title":{"rendered":"Allarme tumori: nel 2025 stimati oltre 362mila nuovi casi, si riduce il divario tra Nord e Sud"},"content":{"rendered":"<p>ROMA &#8211; Nel 2025 in Italia sono stimati 362.100 nuovi tumori, di cui 182.300 casi tra gli uomini e 179.800 tra le donne. \u00c8 quanto emerge dai dati presentati al ministero della Salute dall\u2019Associazione Italiana dei Registri Tumori (<a href=\"https:\/\/www.registri-tumori.it\/cms\/pagine\/airtum-i-tumori-italia\" rel=\"noopener\">Airtum<\/a>), <strong>elaborati su oltre 3 milioni di casi di malattia<\/strong> <strong>oncologica<\/strong> registrati da 34 registri che coprono circa l\u201980% della popolazione italiana.<\/p>\n<h3>Tumori, meno divario tra Nord e Sud<\/h3>\n<p>Uno degli elementi pi\u00f9 significativi riguarda il <strong>progressivo ridursi del divario tra Nord e Sud<\/strong>. Storicamente il Mezzogiorno aveva <strong>un\u2019incidenza pi\u00f9 bassa<\/strong>, ma negli ultimi anni <strong>il vantaggio si sta attenuando<\/strong>. Secondo gli esperti, questo cambiamento \u00e8 legato anche alla diffusione nel Sud di stili di vita meno salutari, che stanno portando a un aumento delle diagnosi. Allo stesso tempo <strong>migliorano le prospettive di cura<\/strong>: cresce infatti la sopravvivenza a <strong>cinque anni dalla diagnosi<\/strong>, anche se permane un divario del 5% a sfavore delle regioni del Sud e delle Isole rispetto al Centro-Nord.<\/p>\n<h3>I tumori pi\u00f9 diffusi in Italia<\/h3>\n<p>Il tumore pi\u00f9 frequente resta quello alla <strong>mammella<\/strong>, con 55.900 nuovi casi stimati. Segue il <strong>tumore al polmone<\/strong> (43.500 casi), <strong>al colon-retto<\/strong> (41.700) e alla <strong>prostata<\/strong> (31.200), il pi\u00f9 diffuso tra gli uomini. Negli <strong>uomini<\/strong> si registra un calo sia dell\u2019incidenza (-1,9% l\u2019anno) sia della mortalit\u00e0 (-1,8%). Nelle <strong>donne<\/strong> la mortalit\u00e0 diminuisce (-0,6%), ma il numero delle nuove diagnosi rimane stabile. A incidere \u00e8 soprattutto la crescita dei tumori al polmone (+2,3%), collegata alla diffusione del fumo. In <strong>diminuzione<\/strong>, invece, i <strong>tumori di fegato, colon-retto e stomaco<\/strong>, mentre \u00e8 in aumento il melanoma. Le donne presentano anche una sopravvivenza pi\u00f9 alta rispetto agli uomini: 74,1% contro 70,7%.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-273576\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Prevenzione_prostata.jpg\" alt=\"tumori prostata\" width=\"550\" height=\"367\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Prevenzione_prostata.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Prevenzione_prostata-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Prevenzione_prostata-768x512.jpg 768w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/p>\n<h3>Tumori pediatrici: sopravvivenza sempre pi\u00f9 alta<\/h3>\n<p>I dati mostrano <strong>segnali incoraggianti anche per i pi\u00f9 giovani<\/strong>. Nei <strong>bambini tra 0 e 14 anni<\/strong> l\u2019incidenza resta stabile e la sopravvivenza raggiunge l\u201985%, in aumento di circa due punti percentuali.\u00a0Tra gli <strong>adolescenti<\/strong> (15-19 anni) si osserva una crescita dei tumori della tiroide e del melanoma, ma la sopravvivenza continua a migliorare, arrivando all\u201989%, senza particolari differenze tra le diverse aree del Paese.<\/p>\n<h3>Il ruolo fondamentale dei registri tumori<\/h3>\n<p>La <strong>raccolta dei dati epidemiologici<\/strong> \u00e8 considerata uno strumento essenziale per comprendere l\u2019andamento delle malattie oncologiche e pianificare le strategie di prevenzione. \u201cI dati contenuti nei <a href=\"https:\/\/quicosenza.it\/news\/tumori-sud-esodo-50-calabria-interventi-seno\/\">registri tumori<\/a> sono uno strumento fondamentale non solo per fotografare la diffusione delle malattie oncologiche, ma anche per programmare gli screening e individuare gli effetti dei fattori di rischio ambientali\u201d, ha spiegato <strong>Fabrizio Stracci<\/strong>, presidente di Airtum.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-285858\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/mappa-registri-tumori-italia.jpg\" alt=\"mappa registri tumori italia\" width=\"708\" height=\"332\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/mappa-registri-tumori-italia.jpg 938w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/mappa-registri-tumori-italia-300x141.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/mappa-registri-tumori-italia-768x360.jpg 768w\" sizes=\"auto, (max-width: 708px) 100vw, 708px\" \/><\/p>\n<p>\u201cLa <strong>copertura \u00e8 migliorata<\/strong> e oggi <strong>raggiunge l\u201980% della popolazione italiana.<\/strong> Ma <strong>alcune regioni devono ancora completare il percorso verso una copertura totale<\/strong>, mentre altre devono superare ostacoli organizzativi o legati alla privacy\u201d. Tra le <a href=\"https:\/\/www.registri-tumori.it\/cms\/registri-tumori\/Registro%20Tumori%20Integrato%20Cosenza%20Crotone\" rel=\"noopener\">regioni<\/a> ancora in fase di completamento figurano Sardegna, Piemonte e Abruzzo, mentre il Molise dovrebbe diventare presto pienamente operativo. Al contrario, alcune realt\u00e0 come Veneto, Campania e Sicilia dispongono da tempo di registri molto completi.<\/p>\n<h3>I dati per individuare i rischi ambientali<\/h3>\n<p>L\u2019analisi dei registri permette anche di <strong>individuare possibili fattori ambientali legati alla diffusione di alcune patologie. <\/strong>\u201cAd esempio \u2013 ha spiegato Stracci \u2013 abbiamo <strong>osservato a Terni<\/strong> un\u2019incidenza di tumori pi\u00f9 alta rispetto ad altre aree: occorre capire quanto possa incidere l\u2019esposizione a particolato o metalli pesanti legati alla presenza dell\u2019industria siderurgica\u201d. Nel <strong>Centro Italia<\/strong>, inoltre, \u00e8 stato registrato un numero maggiore di tumori gastrici associati <strong>all\u2019Helicobacter pylori<\/strong>, <strong>batterio che colpisce lo stomaco<\/strong> ed \u00e8 pi\u00f9 diffuso in alcune aree collinari.\u00a0In passato, proprio grazie ai registri, sono state individuate e studiate situazioni critiche come la <strong>Terra dei Fuochi<\/strong>, le aree vicine <strong>all\u2019Ilva di Taranto e il polo industriale di Porto Marghera<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h3>Schillaci: \u201cNon dobbiamo abbassare la guardia\u201d<\/h3>\n<p>Sul tema \u00e8 intervenuto anche il ministro della Salute <strong>Orazio Schillaci<\/strong>, che ha sottolineato i progressi ottenuti negli ultimi anni. \u201cL\u2019aumento dei tassi di sopravvivenza \u00e8 un risultato straordinario ottenuto grazie all\u2019eccellenza dei centri di oncologia, alle attivit\u00e0 di screening e diagnosi precoce. Restano per\u00f2 aspetti critici\u201d, ha dichiarato il ministro, citando in particolare il <strong>divario tra Sud e Centro-Nord.<\/strong><\/p>\n<p>Schillaci ha inoltre evidenziato l\u2019importanza di una raccolta dati completa e omogenea. \u201cDobbiamo superare la frammentazione dei dati per avere un quadro pi\u00f9 preciso e intervenire selettivamente\u201d. <strong>Il governo \u00e8 al lavoro per rafforzare il sistema di monitoraggio<\/strong>: \u201cAvere dati epidemiologici precisi \u00e8 il punto di partenza per avere strategie mirate e conoscere i dati su base regionale o all\u2019interno della stessa regione. Credo sia importante per continuare nel percorso di lotta ai tumori che abbiamo iniziato dal primo giorno che sono al ministero\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I dati dell\u2019Associazione Italiana dei Registri Tumori: migliorano prevenzione e sopravvivenza. Crescono i tumori al polmone tra le donne e persistono criticit\u00e0 nella raccolta dei dati epidemiologici<\/p>\n","protected":false},"author":42,"featured_media":141472,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-285850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/285850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=285850"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/285850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/141472"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=285850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=285850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=285850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}