{"id":285906,"date":"2026-03-05T17:20:35","date_gmt":"2026-03-05T16:20:35","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=285906"},"modified":"2026-03-05T17:20:35","modified_gmt":"2026-03-05T16:20:35","slug":"provincia-cosenza-caruso-annunci-voto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/provincia-cosenza-caruso-annunci-voto\/","title":{"rendered":"Elezioni Provincia di Cosenza, Caruso: \u201cAnnunci a ridosso del voto? I sindaci non si comprano\u201d"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Prendo atto dell&#8217;importanza dell&#8217;intervento annunciato per la messa in sicurezza della<strong> strada Liboia\u2013Fiumarella,<\/strong> un&#8217;infrastruttura certamente utile alle attivit\u00e0 agricole e produttive di quell&#8217;area. Ogni investimento che migliora la viabilit\u00e0 rurale e sostiene il lavoro degli imprenditori agricoli rappresenta un fatto positivo per i territori e per l&#8217;economia locale&#8221;. E&#8217; quanto afferma<strong> il sindaco Franz Caruso,<a href=\"https:\/\/quicosenza.it\/news\/provincia-di-cosenza-centrosinistra-intesa\/\" target=\"_blank\" rel=\"noopener\"> candidato<\/a> alla presidenza della <a href=\"https:\/\/www.provincia.cs.it\/portale\/\" target=\"_blank\" rel=\"noopener\">Provincia di Cosenza<\/a><\/strong> con riferimento all&#8217;annuncio del finanziamento destinato alla strada interpoderale Liboia\u2013Fiumarella nel territorio di Caloveto.<\/p>\n<h3>Elezioni provincia di Cosenza, Caruso contesta le &#8220;tempistiche dell&#8217;annuncio&#8221;<\/h3>\n<p>&#8220;Non pu\u00f2, tuttavia \u2013 prosegue Franz Caruso &#8211; passare inosservata la <strong>tempistica con cui questo annuncio arriva, a ridosso delle prossime elezioni<\/strong> per la Provincia di Cosenza, nelle quali il <strong>candidato sostenuto dall&#8217;assessore regionale Gianluca Gallo<\/strong> risulta contrapposto alla mia candidatura. Proprio per questo ritengo necessario ribadire un principio che dovrebbe essere patrimonio comune di tutte le istituzioni: l&#8217;azione amministrativa deve essere sempre lineare, sobria e rispettosa dei cittadini, senza mai tracimare nella strumentalit\u00e0 elettorale&#8221;.<\/p>\n<p>Franz Caruso sottolinea, poi, &#8220;una differenza netta di metodo politico che \u00e8 essenziale e fondamentale. Da tempo denunciamo un modello di gestione della cosa pubblica che privilegia dinamiche personalistiche piuttosto che il perseguimento del bene comune. \u00c8 un metodo che abbiamo visto affermarsi negli anni della guida della Provincia da parte di Rosaria Succurro e del suo entourage politico, e che oggi sembra riproporsi nella campagna elettorale che si sta portando avanti&#8221;.<\/p>\n<p>&#8220;Per fortuna non tutti sono uguali e c&#8217;\u00e8 chi, a prescindere dall&#8217;appartenenza politica e partitica, ha a cuore la correttezza amministrativa. <strong>Non \u00e8 un caso che l&#8217;attuale presidente della Provincia abbia gi\u00e0 adottato diversi atti di revoca di provvedimenti assunti dalla precedente gestione guidata dalla presidente Succurro.<\/strong> Si tratta di decisioni che testimoniano come alcune scelte fossero evidentemente discutibili e segnate pi\u00f9 da logiche di parte che da una reale visione di governo del territorio&#8221;.<\/p>\n<p>&#8220;La vera sicurezza, oggi, \u00e8 che i sindaci non si comprano \u2013 conclude Franz Caruso lanciando un chiaro messaggio politico &#8211; I sindaci sono amministratori liberi, responsabili verso le proprie comunit\u00e0 e chiamati a scegliere nell&#8217;interesse dei territori e non sulla base di promesse, pressioni o operazioni di opportunit\u00e0. La Provincia deve tornare ad essere la casa di tutti i comuni, non il luogo dove si consolidano filiere politiche o si costruisce mera appartenenza, peraltro correntizia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco e candidato alla presidenza della Provincia di Cosenza accoglie positivamente il finanziamento per la strada di Caloveto ma attacca sulla tempistica dell\u2019annuncio e sul \u201cmetodo politico\u201d della precedente gestione<\/p>\n","protected":false},"author":58,"featured_media":285313,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42,28],"tags":[],"class_list":["post-285906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/285906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=285906"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/285906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/285313"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=285906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=285906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=285906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}