{"id":28645,"date":"2013-12-21T08:22:23","date_gmt":"2013-12-21T07:22:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28645"},"modified":"2023-01-17T13:26:00","modified_gmt":"2023-01-17T12:26:00","slug":"11994-parco-della-sila-regione-approva-il-progetto-silavoro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/11994-parco-della-sila-regione-approva-il-progetto-silavoro\/","title":{"rendered":"Parco della Sila, Regione approva il progetto &#8220;Silalavoro&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; La commissione di valutazione della Regione Calabria ha approvato il progetto &#8220;Silalavoro&#8221;, presentato dal Parco Nazionale della Sila insieme a Sila Sviluppo Scarl.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&#8220;Il nostro progetto \u00e8 al terzo posto nelle graduatorie pubblicate dalla Commissione di Valutazione della Regione Calabria &#8211; ha dichiarato&nbsp;<span style=\"font-size: 11.818181991577148px;\">Sonia Ferrari, presidente dell&#8217;Ente parco &#8211;&nbsp;<\/span>ed ha ottenuto un finanziamento complessivo di oltre un milione di euro. Si tratta di un risultato importantissimo per il Parco che nei mesi scorsi, quale Ente sovraordinato, ha deciso di sostenere questa iniziativa. Abbiamo subito riconosciuto l&#8217;importanza della tematica alla base dell&#8217;avviso pubblico della Regione Calabria e deciso di garantire l&#8217;assistenza tecnica per l&#8217;elaborazione e la realizzazione del progetto grazie all&#8217;intervento di Giuseppe Paonessa, Ferdinando Verardi e Lillino Citrigno. Inoltre, abbiamo costituito appositamente un partenariato, di cui e&#8217; capofila l&#8217;Unione dei Comuni della Presila, che abbiamo supportato&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>Il risultato raggiunto dal Parco nazionale della Sila ed il ruolo giocato dall&#8217;Ente sono di fatto importantissimi, perch\u00e8 i Piani Locali per il Lavoro (PLL) possono realmente rafforzare le potenzialita&#8217; dei sistemi locali produttivi e creare occupazione qualificante e stabile. Il progetto &#8220;Silavoro&#8221; ha come destinatari le imprese esistenti e i soggetti che prevedono di costituirne di nuove nei settori agro-silvo-pastorale, dell&#8217;artigianato, del turismo, della tutela dell&#8217;ambiente, delle energie rinnovabili e che si occupano di servizi connessi allo sviluppo del territorio nella prospettiva di creare possibili contratti di rete. Infatti, per queste imprese sono previsti incentivi per l&#8217;assunzione a tempo indeterminato di lavoratori svantaggiati, molto svantaggiati o disabili e di giovani laureati calabresi fino a 35 anni, e contributi per la formazione degli apprendisti (giovani dai 15 ai 29 anni). Ora, attraverso un Comitato di coordinamento, nominato dal Partenariato e di cui fanno parte l&#8217;Ente Parco, l&#8217;Unione dei Comuni della Presila, la Provincia di Cosenza, Sila Sviluppo e il Comune di San Giovanni in Fiore, continueranno ad essere gestite tutte le attivita&#8217; previste dal progetto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La commissione di valutazione della Regione Calabria ha approvato il progetto &#8220;Silalavoro&#8221;, presentato dal Parco Nazionale della Sila insieme a Sila Sviluppo Scarl.<\/p>\n","protected":false},"author":19,"featured_media":28646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-28645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28645"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28646"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}