{"id":286538,"date":"2026-03-12T14:09:18","date_gmt":"2026-03-12T13:09:18","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=286538"},"modified":"2026-03-12T14:09:18","modified_gmt":"2026-03-12T13:09:18","slug":"tentata-estorsione-mafiosa-spezzano-san-lorenzo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/tentata-estorsione-mafiosa-spezzano-san-lorenzo\/","title":{"rendered":"Tentata estorsione mafiosa a 2 imprese per lavori a Spezzano e San Lorenzo del Vallo. In carcere 2 persone"},"content":{"rendered":"<p><strong>COSENZA<\/strong> \u2013 Tentata estorsione con metodo mafioso.\u00a0Nella mattinata odierna, i <strong>Carabinieri della Compagnia di San Marco Argentano<\/strong> hanno dato esecuzione a un\u2019ordinanza d<strong>i custodia cautelare in carcere<\/strong> nei confronti di due persone, indagate per <strong>tentata estorsione aggravata dal metodo mafioso<\/strong>.\u00a0Il provvedimento, emesso dal GIP presso il Tribunale di Catanzaro su richiesta della <strong>Procura della Repubblica &#8211; Direzione Distrettuale Antimafia (DDA)<\/strong>, colpisce il fenomeno del racket che soffoca l&#8217;imprenditoria locale e il settore degli appalti pubblici.<\/p>\n<h3><strong>Nel mirino lavori pubblici a Spezzano Albanese e San Lorenzo del Vallo<\/strong><\/h3>\n<p>L\u2019attivit\u00e0 d\u2019indagine, coordinata dai magistrati della DDA di Catanzaro, ha fatto luce su due specifici episodi criminosi che delineano un quadro di forte pressione ambientale sul territorio. Secondo quanto emerso dalle indagini, gli indagati avrebbero preso di mira due importanti interventi edilizi. A <strong>Spezzano Albanese<\/strong>\u00a0le pressioni avrebbero riguardato la ditta aggiudicatrice dell\u2019appalto per la <strong>posa in opera di porfido nel centro storico<\/strong>. A <strong>San Lorenzo del Vallo<\/strong> sarebbe finita \u00a0nel mirino l\u2019impresa incaricata dei lavori di ricostruzione del <strong>nuovo plesso della scuola per l\u2019infanzia<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-281827 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Carabinieri.jpg\" alt=\"Carabinieri rapina bar\" width=\"588\" height=\"393\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Carabinieri.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Carabinieri-300x200.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/Carabinieri-768x513.jpg 768w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/><\/p>\n<p><strong>Il &#8220;Modus Operandi&#8221;: minacce e metodo mafioso<\/strong><\/p>\n<p>In entrambi i casi, lo schema criminale seguito \u00e8 stato quello classico e consolidato delle consorterie di stampo mafioso. Gli indagati avrebbero richiesto il v<strong>ersamento di somme di denaro non dovute<\/strong>, utilizzando la <strong>minaccia implicita di gravi ritorsioni<\/strong> in caso di mancata adesione.<\/p>\n<p>L\u2019aggravante del <a href=\"https:\/\/quicosenza.it\/news\/estorsioni-metodo-mafioso-due-arresti\/\" target=\"_blank\" rel=\"noopener\"><strong>metodo mafioso<\/strong> <\/a>e della finalit\u00e0 di <strong>agevolazione mafiosa<\/strong> evidenzia, secondo l&#8217;accusa, la volont\u00e0 di <strong>riaffermare il controllo del territorio attraverso l&#8217;intimidazione e il condizionamento delle attivit\u00e0 economiche legal<\/strong>i, in particolare quelle legate ai fondi pubblici per le infrastrutture cittadine.\u00a0Il procedimento per le fattispecie di reato ipotizzate \u00e8 attualmente nella fase delle indagini preliminari.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Colpo al racket delle estorsioni tra Spezzano Albanese e San Lorenzo del Vallo. I Carabinieri eseguono due ordinanze di custodia cautelare su ordine della Procura Distrettuale Antimafia di Catanzaro<\/p>\n","protected":false},"author":55,"featured_media":286539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-286538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/286538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=286538"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/286538\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/286539"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=286538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=286538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=286538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}