{"id":286845,"date":"2026-03-16T11:51:35","date_gmt":"2026-03-16T10:51:35","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=286845"},"modified":"2026-03-16T12:12:00","modified_gmt":"2026-03-16T11:12:00","slug":"maltempo-piragineti-stop-attivita-scuola","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/maltempo-piragineti-stop-attivita-scuola\/","title":{"rendered":"Maltempo, a Piragineti infliltrazioni nelle classi: Stasi ordina la sospensione dell&#8217;attivit\u00e0 didattica"},"content":{"rendered":"<p>CORIGLIANO ROSSANO (CS) &#8211; Ore difficili in tutta la Calabria per via del <a href=\"https:\/\/quicosenza.it\/news\/statale-106-jonica-chiusa-amendolara-galleria\/\" target=\"_blank\" rel=\"noopener\">maltempo<\/a>, con <a href=\"https:\/\/quicosenza.it\/news\/maltempo-60-interventi-vigili-fuoco-cosenza\/\" target=\"_blank\" rel=\"noopener\"><strong>oltre 60 interventi<\/strong> <\/a>effettuati dai Vigili del Fuoco dalle prime ore dell&#8217;alba. Nel Cosentino la situazione pi\u00f9 delicata \u00e8 a Cosenza ma senza criticit\u00e0 estreme.<\/p>\n<p>Nel Comune di<strong> Corigliano Rossano,<\/strong> nonostante non ci siano situazioni di allerta, come avvenuto nelle settimane scorse, per via di <strong>infiltrazioni dalla pavimentazione,<\/strong> il sindaco <a href=\"https:\/\/www.facebook.com\/flavio.stasi.sindaco\" target=\"_blank\" rel=\"noopener\">Flavio Stasi<\/a> ha emanato ordinanza di<strong> sospensione delle attivit\u00e0 didattiche<\/strong> nel <strong>plesso dell&#8217;infanzia di Piragineti. <\/strong><\/p>\n<p>Lo stop all&#8217;attivit\u00e0 \u00e8 previsto per <strong>oggi 16 marzo, e domani, 17 marzo,<\/strong> finalizzata a consentire gli interventi per l&#8217;individuazione della fonte del problema e la relativa soluzione.<\/p>\n<h3>Maltempo, nessuna criticit\u00e0 sulla viabilit\u00e0<\/h3>\n<p>Sul fronte della viabilit\u00e0 la situazione resta tranquilla. L&#8217;amministrazione fa sapere che non \u00e8 stato necessario interdire alcun tratto di viabilit\u00e0 comunale, compresi i sottopassi ferroviari, i quali restano comunque sotto osservazione. Sono attivi tutti gli impianti idrovori presenti sulle aree urbanizzate depresse ed al momento non si registrano criticit\u00e0 rilevanti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per via di infiltrazioni dalla pavimentazione, il sindaco ha emanato ordinanza per il plesso dell&#8217;infanzia che ferma l&#8217;attivit\u00e0 per oggi 16 marzo, e domani, 17 marzo<\/p>\n","protected":false},"author":90,"featured_media":286849,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[],"class_list":["post-286845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/286845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=286845"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/286845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/286849"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=286845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=286845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=286845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}