{"id":287330,"date":"2026-03-21T09:23:41","date_gmt":"2026-03-21T08:23:41","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=287330"},"modified":"2026-03-21T09:23:41","modified_gmt":"2026-03-21T08:23:41","slug":"docente-spartaco-pupo-musei-nazionali-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/docente-spartaco-pupo-musei-nazionali-calabria\/","title":{"rendered":"Il docente UniCal Spartaco Pupo nel Comitato scientifico dei Musei nazionali Calabria"},"content":{"rendered":"<p>RENDE &#8211; Il docente cosentino dell\u2019<a href=\"https:\/\/quicosenza.it\/news\/le-mafie-cercano-il-consenso-della-chiesa\/\">UniCal<\/a>, <strong>Spartaco Pupo<\/strong>, \u00e8 stato nominato componente del <strong>Comitato scientifico della Direzione regionale Musei nazionali Calabria<\/strong>, che ha sede nel complesso monumentale di <a href=\"https:\/\/musei.calabria.beniculturali.it\/musei?mid=80&amp;nome=galleria-nazionale-di-cosenza\" rel=\"noopener\">Palazzo Arnone<\/a> a Cosenza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-123737 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/1237206116240_1_palazzo_arnone-3.jpg\" alt=\"Il docente UniCal Spartaco Pupo nel Comitato scientifico dei Musei nazionali Calabria\" width=\"395\" height=\"288\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/1237206116240_1_palazzo_arnone-3.jpg 442w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/1237206116240_1_palazzo_arnone-3-300x219.jpg 300w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><\/p>\n<h3>Spartaco Pupo \u00e8 docente presso il Dipartimento di Scienze Politiche e Sociali UniCal<\/h3>\n<p>Professore presso il Dipartimento di Scienze Politiche e Sociali dell\u2019UniCal, <strong>Pupo \u00e8 stato designato dal ministro della Cultura, Alessandro Giuli<\/strong>. L\u2019organismo, con durata quinquennale, opera a supporto della Direzione regionale, che coordina, valorizza e gestisce musei, parchi archeologici e luoghi della cultura statali in Calabria, promuovendone la conoscenza, l\u2019accessibilit\u00e0 e l\u2019integrazione con il territorio.<\/p>\n<p><strong>Studioso e autore di numerosi libri e articoli scientifici<\/strong>, Pupo \u00e8 anche membro di istituti e centri di ricerca nazionali e internazionali. La sua nomina rafforza il legame tra il mondo della ricerca universitaria e le istituzioni impegnate nella tutela e nella promozione del patrimonio culturale calabrese.<\/p>\n<p>A comporre il Comitato, come previsto dalla normativa sull\u2019organizzazione dei musei statali, sono inoltre <strong>Carmelo Malacrino<\/strong>, designato dal Consiglio superiore per i beni culturali e paesaggistici, A<strong>nna Cipparrone<\/strong>, indicata dalla Regione Calabria, e <strong>Maria Cerzoso<\/strong>, designata dal Comune di Cosenza, ente nel cui territorio ha sede la Direzione regionale.<\/p>\n<p>\u201cQuesta designazione ministeriale rappresenta un <strong>riconoscimento significativo<\/strong> sia sul piano scientifico sia su quello culturale \u2013 ha dichiarato Pupo \u2013 oltre a costituire un\u2019importante occasione di servizio per la<strong> Calabria<\/strong>, in una fase in cui la valorizzazione dei luoghi della cultura assume un ruolo sempre pi\u00f9 centrale per la crescita civile e l\u2019immagine del territorio&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-200478 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Unical-Universita-della-Calabria-02.jpg\" alt=\"Unical Universit\u00e0 della Calabria\" width=\"467\" height=\"289\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Unical-Universita-della-Calabria-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Unical-Universita-della-Calabria-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Unical-Universita-della-Calabria-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Unical-Universita-della-Calabria-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Unical-Universita-della-Calabria-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Unical-Universita-della-Calabria-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Unical-Universita-della-Calabria-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 467px) 100vw, 467px\" \/><\/p>\n<p>&#8220;Sono onorato \u2013 ha aggiunto il docente dell\u2019Universit\u00e0 della Calabria \u2013 di rappresentare il Ministero in questo importante organismo istituzionale, consapevole del valore che il patrimonio museale calabrese riveste per la storia e la vita culturale dell\u2019intero Paese. Avverto pienamente la responsabilit\u00e0 morale e civile di operare a tutela di quella che considero la vera identit\u00e0 della Calabria\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nomina del docente dell\u2019UniCal Spartaco Pupo nel Comitato scientifico dei Musei nazionali Calabria, \u00e8 stata firmata dal ministro della Cultura Alessandro Giuli<\/p>\n","protected":false},"author":66,"featured_media":287331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-287330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/287330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=287330"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/287330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/287331"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=287330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=287330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=287330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}