{"id":287883,"date":"2026-03-27T07:18:34","date_gmt":"2026-03-27T06:18:34","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=287883"},"modified":"2026-03-27T09:24:46","modified_gmt":"2026-03-27T08:24:46","slug":"carabinieri-penna-pistola-salotto-un-arresto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/carabinieri-penna-pistola-salotto-un-arresto\/","title":{"rendered":"Carabinieri scoprono una penna-pistola in salotto, durante una perquisizione: un arresto"},"content":{"rendered":"<p>RIACE (RC) &#8211; Una penna-pistola, un oggetto apparentemente comune che nasconde per\u00f2 un\u2019arma. In un primo momento pu\u00f2 sembrare semplicemente una penna, soprattutto se adagiata tra altri oggetti in un salotto di una casa come tante.<\/p>\n<h3>La penna-pistola scoperta durante la perquisizione<\/h3>\n<p>Impegnati in un\u2019attivit\u00e0 di perquisizione, infatti, i carabinieri di Riace non si sono lasciati trarre in inganno dalle apparenze, scoprendo cos\u00ec che si trattava di una \u201c<a href=\"https:\/\/quicosenza.it\/news\/armi-clandestine-penna-pistola-arrestato\/\">penna-pistola<\/a>\u201d, <strong>dotata di tutti quei meccanismi che la rendono identica<\/strong>, nel suo funzionamento,<strong> ad un\u2019arma da fuoco.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-287885\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/penna-pistola-carabinieri-riace-02.jpg\" alt=\"penna-pistola carabinieri riace 02\" width=\"580\" height=\"359\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/penna-pistola-carabinieri-riace-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/penna-pistola-carabinieri-riace-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/penna-pistola-carabinieri-riace-02-768x475.jpg 768w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/p>\n<p>\u00c8 proprio quella sua semplicit\u00e0 a renderla tanto pi\u00f9 pericolosa e, soprattutto, insidiosa: pu\u00f2 essere infatti <strong>trasportata ed occultata con pochissimi accorgimenti,<\/strong> e sottratta con facilit\u00e0 ai controlli.<\/p>\n<h3>Un\u2019arma pronta all\u2019uso<\/h3>\n<p>L\u2019uomo, arrestato dai militari, dovr\u00e0 ora spiegare come mai custodisse l\u2019arma insieme a diverse munizioni, una delle quali rinvenuta proprio all\u2019interno del dispositivo, apparentemente pronta ad essere utilizzata. Un dettaglio che evidenzia la potenziale pericolosit\u00e0 della situazione e la prontezza operativa dell\u2019arma clandestina.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-287886\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/penna-pistola-carabinieri-riace-03.jpg\" alt=\"penna-pistola carabinieri riace 03\" width=\"648\" height=\"401\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/penna-pistola-carabinieri-riace-03.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/penna-pistola-carabinieri-riace-03-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/penna-pistola-carabinieri-riace-03-768x475.jpg 768w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><\/p>\n<h3>Non \u00e8 un caso isolato<\/h3>\n<p>Ma questo, i Carabinieri, lo sanno bene. D\u2019altronde, non \u00e8 la prima arma clandestina di questo tipo che viene trovata nella stessa zona: appena pochi mesi fa, infatti, nel <strong>limitrofo Comune di <a href=\"https:\/\/www.carabinieri.it\/in-vostro-aiuto\/informazioni\/comunicati-stampa\/deteneva-armi-clandestine-e-una-penna-pistola.-arrestato-un-uomo\" rel=\"noopener\">Camini<\/a> (Rc),<\/strong> gli stessi militari si erano imbattuti in un altro manufatto assai simile e anche in quel caso erano scattate le manette.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un oggetto all\u2019apparenza innocuo, una penna-pistola, clandestina e pronta all\u2019uso. I Carabinieri scoprono il dispositivo durante una perquisizione: non \u00e8 il primo caso nella zona<\/p>\n","protected":false},"author":42,"featured_media":287884,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-287883","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/287883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=287883"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/287883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/287884"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=287883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=287883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=287883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}