{"id":28793,"date":"2013-12-29T06:18:41","date_gmt":"2013-12-29T05:18:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28793"},"modified":"2023-01-17T13:26:09","modified_gmt":"2023-01-17T12:26:09","slug":"12070-a-reggio-calabria-buon-anno-con-aisla","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12070-a-reggio-calabria-buon-anno-con-aisla\/","title":{"rendered":"A Reggio Calabria \u201cBuon anno con AISLA\u201d"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; La sezione di Reggio Calabria di AISLA, l\u2019Associazione Italiana Sclerosi Laterale Amiotrofica, saluta il 2013 con due iniziative di raccolta fondi che uniscono sport e buona cucina.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Oggi, domenica 29 dicembre l\u2019Associazione Amatori Calcio Chorio e gli \u201cAmici di Cecio\u201d hanno organizzato presso lo stadio comunale \u201cAv. P. Catanoso\u201d di Chorio di San Lorenzo (Rc) la quinta edizione del Memorial calcistico \u201cVincenzo Infortuna\u201d, con la partecipazione dei \u201cmuso puniti\u201d, \u201camatori calcio chorio\u201d e \u201cassociazione arbitri Reggio Calabria\u201d. Al Memorial, che \u00e8 dedicato al ricordo di Vincenzo Infortuna, padre di Manuela Infortuna consigliera della sezione AISLA di Reggio Calabria, sar\u00e0 presente il Vicepresidente nazionale di Aisla, Vincenzo Soverino. Nell\u2019occasione saranno raccolti fondi per le attivit\u00e0 che la sezione Aisla di Reggio Calabria svolge sul territorio a sostegno dei malati. Dalle ore 13 di oggi invece, la sezione reggina dell&#8217;Aisla organizza all&#8217;Agriturismo \u201cPorta del Parco di Bagaladi\u201d il primo pranzo augurale \u201cBuon Anno con Aisla\u201d. Parte del ricavato del pranzo sar\u00e0 donato dall&#8217;agriturismo ad Aisla.<\/p>\n<p>&nbsp;<\/p>\n<p>AISLA Onlus nasce nel 1983 con l\u2019obiettivo di diventare il soggetto nazionale di riferimento per la tutela, l\u2019assistenza e la cura dei malati di SLA, favorendo l\u2019informazione, la ricerca e la formazione sulla malattia e stimolando le strutture competenti a una presa in carico adeguata e qualificata dei malati.L\u2019Associazione attualmente conta 60 rappresentanze territoriali in 19 regioni italiane e circa 1636 soci grazie al lavoro di oltre 200 volontari e di 8 collaboratori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; La sezione di Reggio Calabria di AISLA, l\u2019Associazione Italiana Sclerosi Laterale Amiotrofica, saluta il 2013 con due iniziative di raccolta fondi che uniscono sport e buona cucina.<\/p>\n","protected":false},"author":22,"featured_media":28794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-28793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28793"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28794"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}