{"id":28807,"date":"2013-12-28T09:46:54","date_gmt":"2013-12-28T08:46:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=28807"},"modified":"2023-01-17T13:26:10","modified_gmt":"2023-01-17T12:26:10","slug":"12077-muore-dopo-che-i-sanitari-lo-hanno-rimandato-a-casa-avviata-inchiesta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12077-muore-dopo-che-i-sanitari-lo-hanno-rimandato-a-casa-avviata-inchiesta\/","title":{"rendered":"I medici lo rimandano a casa e muore d&#8217;infarto, avviata inchiesta"},"content":{"rendered":"<p>COSENZA &#8211; Nuovo presunto caso di malasanit\u00e0 nel Cosentino.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La procura della Repubblica di Cosenza ha aperto un\u2019inchiesta sulla morte, avvenuta il giorno della vigilia di Natale, di Francesco Scalise, 42 anni, di San Giovanni in Fiore.&nbsp;L&#8217;uomo, sposato e padre di quattro figli, il giorno prima s\u2019era recato nell\u2019ospedale di San Giovanni in Fiore, lamentando dei dolori al petto e ad un braccio. Il medico di turno, ha raccontato la moglie dell\u2019uomo, avrebbe curato il marito con farmaci antinfiammatori, rimandandolo a casa dopo l\u2019elettrocardiogramma. Durante la notte per\u00f2, Scalise ha avvertito dolori pi\u00f9 forti e la mattina successiva la moglie l\u2019ha caricato in auto per portarlo a Crotone, ma il 42enne \u00e8 morto senza riuscire ad arrivare in ospedale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Nuovo presunto caso di malasanit\u00e0 nel Cosentino.<\/p>\n","protected":false},"author":19,"featured_media":28808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-28807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=28807"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/28807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/28808"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=28807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=28807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=28807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}