{"id":288397,"date":"2026-04-01T08:36:45","date_gmt":"2026-04-01T06:36:45","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=288397"},"modified":"2026-04-01T08:36:45","modified_gmt":"2026-04-01T06:36:45","slug":"carlo-tansi-protezione-civile-lillegittimita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/carlo-tansi-protezione-civile-lillegittimita\/","title":{"rendered":"Carlo Tansi rimosso dalla Protezione civile nel 2018, il Tribunale del Lavoro riconosce l\u2019illegittimit\u00e0"},"content":{"rendered":"<p>CATANZARO &#8211; Una sentenza del Tribunale del lavoro di Catanzaro riporta al centro del dibattito la vicenda dell\u2019ex responsabile della Protezione Civile della Calabria, Carlo Tansi. Secondo quanto riferito dallo stesso <a href=\"https:\/\/www.facebook.com\/CarloTansi1962\" rel=\"noopener\">Tansi sui social<\/a>, il giudice ha stabilito che nel 2018 la sua rimozione dall\u2019incarico \u00e8 avvenuta in modo illegittimo.<\/p>\n<h3>Carlo Tansi: &#8220;sentenza definitiva&#8221;<\/h3>\n<p>&#8220;Il Tribunale del lavoro di Catanzaro, con una sentenza definitiva, ha stabilito <strong>che nel 2018 sono stato cacciato dalla guida della Protezione Civile della Calabria in modo illegittimo e senza alcun fondamento<\/strong>&#8220;. Nel suo post, Tansi ha ripercorso i <strong>tre anni<\/strong> alla guida della struttura regionale, dal 2<strong>015 al 2018 <\/strong>evidenziando di aver introdotto <strong>controlli, regole e interventi di riorganizzazione<\/strong>, con l\u2019obiettivo di rendere pi\u00f9 <strong>trasparente ed efficiente la gestione delle risorse pubbliche. <\/strong>Tra le attivit\u00e0 ricordate, la modernizzazione della Sala Operativa Regionale, la creazione del sistema informativo <strong>WebSor<\/strong> e dell\u2019app \u201c<a href=\"https:\/\/quicosenza.it\/news\/218379-la-protezione-civile-di-tansi-premiata-a-roma-al-forum-pa-2018\/\">Easy Alert<\/a>\u201d, oltre alla riforma del sistema di volontariato e alla redazione di importanti strumenti di pianificazione.<\/p>\n<p>La riorganizzazione avrebbe prodotto anche risparmi economici significativi e miglioramenti operativi. La struttura, ha sottolineato Tansi, sarebbe stata riconosciuta come modello a livello nazionale, ricevendo apprezzamenti anche dal Dipartimento nazionale della Protezione Civile.\u00a0Nel periodo del suo incarico sono stati inoltre ottenuti <strong>riconoscimenti istituzionali e premi per l\u2019innovazione tecnologica<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-129747\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/carlo-tansi-11.jpg\" alt=\"carlo tansi\" width=\"468\" height=\"263\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/carlo-tansi-11.jpg 900w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/carlo-tansi-11-300x169.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/carlo-tansi-11-768x432.jpg 768w\" sizes=\"auto, (max-width: 468px) 100vw, 468px\" \/><\/p>\n<h3>La vicenda della rimozione<\/h3>\n<p>Tansi ha ricostruito anche le fasi che portarono alla sua sospensione e successiva rimozione, avvenuta poco prima della scadenza del contratto. &#8220;La <a href=\"https:\/\/quicosenza.it\/news\/263272-protezione-civile-scade-madnto-di-tansi-si-cerca-dirigente-esterno\/\">sospensione<\/a> mi fu comunicata un <strong>giorno prima della scadenza del contratto<\/strong>, impedendomi perfino di fare ricorso nei tempi utili&#8221;. Una situazione che, secondo quanto dichiarato, avrebbe avuto anche un impatto personale rilevante.\u00a0Nel suo racconto, l\u2019ex responsabile ha fatto riferimento al <strong>contesto istituzionale e alle dinamiche che accompagnarono quel periodo<\/strong>, citando anche <strong>procedimenti giudiziari e controversie ancora in corso<\/strong>.\u00a0Tra questi, un processo per diffamazione che coinvolge l\u2019ex consigliere regionale Domenico Tallini, con una prossima udienza fissata <strong>per il 2 aprile.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-94439\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/tansi-protezione-civile-1.jpg\" alt=\"\" width=\"482\" height=\"310\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/tansi-protezione-civile-1.jpg 735w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/tansi-protezione-civile-1-300x193.jpg 300w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/><\/p>\n<h3>\u201cUna vicenda che riguarda i cittadini\u201d<\/h3>\n<p>Tansi ha infine sottolineato il valore pubblico della vicenda: &#8220;non \u00e8 una opinione. \u00c8 una sentenza definitiva. Questa non \u00e8 solo una vicenda personale. Riguarda il diritto dei calabresi a sapere cosa succede quando qualcuno prova davvero a eliminare privilegi, fermare sprechi e riportare legalit\u00e0&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ex responsabile della Protezione Civile regionale ricostruisce la vicenda e il lavoro svolto: \u201cNon \u00e8 una opinione. \u00c8 una sentenza definitiva\u201d<\/p>\n","protected":false},"author":42,"featured_media":284440,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-288397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/288397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=288397"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/288397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/284440"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=288397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=288397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=288397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}