{"id":288600,"date":"2026-04-03T09:00:07","date_gmt":"2026-04-03T07:00:07","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=288600"},"modified":"2026-04-03T10:40:38","modified_gmt":"2026-04-03T08:40:38","slug":"calabria-rai-1-sport-salute-cosentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/calabria-rai-1-sport-salute-cosentino\/","title":{"rendered":"La Calabria ritorna protagonista su Rai 1: sport e salute tra la Costa degli Dei e il Cosentino"},"content":{"rendered":"<p>COSENZA &#8211; Domani, sabato<strong> 4 aprile,<\/strong> alle 11:25, &#8220;Linea Verde Illumina \u2013 Sport e Salute&#8221; <a href=\"https:\/\/quicosenza.it\/news\/calabria-rai-1-cosenza-saracena-protagoniste\/\" target=\"_blank\" rel=\"noopener\">torna a parlare della Calabria.<\/a> Il programma condotto da Francesco Gasparri proporr\u00e0 un viaggio emozionante tra le province di Cosenza e Vibo Valentia, mettendo al centro il legame indissolubile tra bellezza paesaggistica e benessere fisico. La regione viene attraversata con tre leggende dello sport italiano per promuovere corretti stili di vita e inclusione sociale.<\/p>\n<p>La Calabria cos\u00ec si trasforma in una palestra a cielo aperto.\u00a0Ad accompagnare Gasparri in questa tappa calabrese ci saranno tre pesi massimi dello sport azzurro, membri del Team Illumina: il judoka<strong> Pino Maddaloni,<\/strong> il pallavolista<strong> Valerio Vermiglio<\/strong> e l\u2019icona del pugilato <strong>Patrizio Oliva.<\/strong><\/p>\n<h3>La Calabria ancora su Rai 1: dal mare all&#8217;altopiano nel Vibonese<\/h3>\n<p>Il viaggio inizier\u00e0 a pochi passi dalla celebre Tropea. In sella alle biciclette, Francesco Gasparri e Patrizio Oliva percorreranno l\u2019itinerario ad anello che unisce i comuni di<strong> Drapia, Zungri e Zaccanopoli.<\/strong> Un bike tour suggestivo che collegher\u00e0 idealmente la &#8220;Costa degli Dei&#8221; con l\u2019Altopiano del Poro, dimostrando come il <strong>cicloturismo<\/strong> sia la chiave perfetta per valorizzare il territorio in modo sostenibile.<\/p>\n<h3>Sport e inclusione: spazio all&#8217;Universit\u00e0 della Calabria e non solo<\/h3>\n<p>La tappa cosentina far\u00e0 scalo al <strong>Cus dell\u2019Universit\u00e0 della Calabria.<\/strong> Qui il focus si sposter\u00e0 sulla <strong>funzione sociale dell&#8217;attivit\u00e0 motoria.<\/strong> Insieme a Valerio Vermiglio, si parler\u00e0 del progetto <strong>\u201cVoucher per lo sport\u201d<\/strong>: un\u2019iniziativa concreta che, tramite contributi economici basati sul reddito, permette ai giovani di accedere alla pratica dilettantistica, rendendo lo sport un diritto realmente accessibile e inclusivo.<\/p>\n<p>Il racconto toccher\u00e0 poi il borgo di<strong> Aiello Calabro,<\/strong> dove Gasparri e Pino Maddaloni presenteranno \u201cAiello in bici\u201d, un\u2019iniziativa che promuove camminate e pedalate come strumenti di salute per residenti e turisti.<\/p>\n<p>Infine, per la rubrica \u201cBenessere e Territorio\u201d, Elisa Silvestrin e Andrea Lo Cicero si sposteranno nel reggino tra bergamotto e sport acquatici. Vedremo una suggestiva uscita in catamarano nello Stretto e l&#8217;adrenalina del kite surf tra le onde di Punta Pellaro.<\/p>\n<h3>Una sinergia istituzionale<\/h3>\n<p>Il programma \u00e8 realizzato in collaborazione con &#8220;Sport e Salute&#8221;, la Regione Calabria \u2013 Dipartimento Turismo e la <a href=\"https:\/\/www.facebook.com\/calabriafilmcommission\" target=\"_blank\" rel=\"noopener\">Fondazione Calabria Film Commission<\/a>, a conferma di quanto la regione stia puntando sul binomio sport-turismo per il proprio rilancio internazionale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domani, 4 aprile, in tv un viaggio emozionante tra le province di Cosenza e Vibo Valentia, mettendo al centro il legame indissolubile tra bellezza paesaggistica e benessere fisico <\/p>\n","protected":false},"author":90,"featured_media":288603,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-288600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/288600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=288600"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/288600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/288603"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=288600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=288600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=288600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}