{"id":288784,"date":"2026-04-04T13:49:51","date_gmt":"2026-04-04T11:49:51","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=288784"},"modified":"2026-04-04T13:49:51","modified_gmt":"2026-04-04T11:49:51","slug":"giallo-a-scilla-un-cadavere-rinvenuto-nelle-acque-del-porto-indagini-in-corso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/giallo-a-scilla-un-cadavere-rinvenuto-nelle-acque-del-porto-indagini-in-corso\/","title":{"rendered":"Giallo a Scilla: un cadavere rinvenuto nelle acque del porto. Indagini in corso"},"content":{"rendered":"<p>SCILLA (RC) &#8211; Un inizio di giornata drammatico ha scosso la comunit\u00e0 di <strong>Scilla<\/strong>, nel reggino. Nella mattinata di oggi, <strong>4 aprile 2026<\/strong>, alcuni cittadini presenti nell&#8217;area portuale hanno notato la presenza di un corpo senza vita affiorante dallo specchio d&#8217;acqua.\u00a0L&#8217;allarme \u00e8 scattato immediatamente: sul posto sono intervenuti gli uomini della <strong>Capitaneria di Porto<\/strong> per il r<strong>ecupero della salma<\/strong>, insieme ai Carabinieri e al medico legale per i primi accertamenti esterni.<\/p>\n<h3><strong>La vittima potrebbe essere un commerciante della zona<\/strong><\/h3>\n<p>Secondo le prime indiscrezioni trapelate, il cadavere appartiene a un <strong>uomo di mezza et\u00e0<\/strong>, presumibilmente di nazionalit\u00e0 italiana. Sebbene l&#8217;identificazione ufficiale sia ancora in corso, alcune testimonianze suggeriscono che possa trattarsi di un <strong>esercente non residente a Scilla<\/strong>, ma conosciuto nella zona. Pare che alcuni conoscenti abbiano gi\u00e0 effettuato un primo, informale riconoscimento della salma. La <strong>Procura della Repubblica di Reggio Calabria<\/strong> \u00e8 stata immediatamente informata dell&#8217;accaduto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-207945 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/Guardia-Costiera2.jpg\" alt=\"Guardia Costiera\" width=\"620\" height=\"398\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/Guardia-Costiera2.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/Guardia-Costiera2-300x193.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/Guardia-Costiera2-768x493.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/Guardia-Costiera2-150x96.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/Guardia-Costiera2-696x447.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/07\/Guardia-Costiera2-654x420.jpg 654w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<h3><strong>Le indagini della Procura: si attende l&#8217;autopsia<\/strong><\/h3>\n<p>Il pubblico ministero di turno ha assunto il coordinamento delle indagini per fare luce sulla dinamica del decesso. Al momento, gli inquirenti mantengono il massimo riserbo e <strong>non escludono alcuna ipotesi<\/strong>, dal malore fatale al gesto volontario, fino a cause di natura diversa. Nelle prossime ore il magistrato dovrebbe disporre l&#8217;<strong>esame autoptico<\/strong>, passaggio fondamentale per stabilire con certezza le cause della morte e l&#8217;ora del decesso.<\/p>\n<p>Per ricostruire gli ultimi istanti di vita dell&#8217;uomo, gli investigatori stanno procedendo all&#8217;acquisizione dei filmati dei <strong>sistemi di videosorveglianza<\/strong> pubblici e privati presenti in tutta l&#8217;area del porto di Scilla. I video potrebbero rivelare se l&#8217;uomo fosse solo al momento dell&#8217;arrivo in banchina e come sia finito in acqua<strong>.\u00a0La zona del ritrovamento \u00e8 stata temporaneamente isolata per permettere i rilievi tecnici necessari<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La scoperta all&#8217;alba di oggi nel noto borgo della Costa Viola. Il corpo di un uomo di mezza et\u00e0 \u00e8 stato recuperato nel porto<\/p>\n","protected":false},"author":55,"featured_media":288785,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-288784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/288784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=288784"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/288784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/288785"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=288784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=288784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=288784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}