{"id":290053,"date":"2026-04-17T07:55:44","date_gmt":"2026-04-17T05:55:44","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=290053"},"modified":"2026-04-17T07:55:44","modified_gmt":"2026-04-17T05:55:44","slug":"bonus-truffa-crediti-fantasma-5-indagati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/bonus-truffa-crediti-fantasma-5-indagati\/","title":{"rendered":"Bonus ristrutturazioni: maxi truffa da 3,2 milioni. Crediti edilizi fantasma, 5 indagati"},"content":{"rendered":"<p>CATANZARO &#8211; Crediti d&#8217;imposta legati al \u201c<a href=\"https:\/\/quicosenza.it\/news\/superbonus-lavori-mai-terminati-tre-indagati\/\">Bonus ristrutturazioni<\/a>\u201d interventi mai realizzati. Maxi operazione della Guardia di Finanza nel Catanzarese contro una presunta associazione per delinquere finalizzata alla creazione di crediti d\u2019imposta inesistenti. Eseguito un decreto di sequestro preventivo per <strong>oltre 3 milioni di euro<\/strong>, cui si aggiunge <strong>il profitto<\/strong> del reato stimato in circa 1,6 milioni di euro. Il provvedimento, richiesto d\u2019urgenza e successivamente convalidato dal GIP del Tribunale di Catanzaro, riguarda crediti fittizi presenti nei cassetti fiscali per un totale di 3.241.072 euro.<\/p>\n<h3>Bonus ristrutturazioni, il sistema dei crediti fittizi<\/h3>\n<p>Al centro dell\u2019indagine un<strong> soggetto residente a Soverato<\/strong>, ritenuto figura chiave del sistema illecito. Attraverso la propria ditta individuale, formalmente incaricata di eseguire lavori di ristrutturazione edilizia, avrebbe generato crediti d\u2019imposta legati al \u201c<a href=\"https:\/\/www.agenziaentrate.gov.it\/portale\/schede\/agevolazioni\/detrristredil36\/schinfodetrristredil36\" rel=\"noopener\">Bonus<\/a> ristrutturazioni\u201d senza che venissero realizzati interventi reali. I crediti venivano poi ceduti tra diverse imprese riconducibili al sodalizio, spesso a prezzi ribassati o addirittura gratuitamente, per essere successivamente monetizzati presso istituti di credito.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-277882\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/evasione-fiscale-guardia-finanza-cosenza-02.jpg\" alt=\"cosca arena guardia finanza contraffazione bonus\" width=\"495\" height=\"306\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/evasione-fiscale-guardia-finanza-cosenza-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/evasione-fiscale-guardia-finanza-cosenza-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/12\/evasione-fiscale-guardia-finanza-cosenza-02-768x475.jpg 768w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/p>\n<h3>Indagini e ricostruzione dei flussi<\/h3>\n<p>L\u2019attivit\u00e0 investigativa, condotta dal <strong>Nucleo di Polizia Economico-Finanziaria di Catanzaro<\/strong>, si \u00e8 concentrata sulla dimostrazione dell\u2019inesistenza dei lavori edilizi e sulla ricostruzione dei flussi finanziari legati alla circolazione dei crediti. Le indagini hanno permesso di raccogliere gravi indizi sull\u2019esistenza di un\u2019organizzazione strutturata finalizzata alla truffa ai danni dello Stato.<\/p>\n<p><strong>Cinque persone fisiche sono state denunciate <\/strong>all\u2019Autorit\u00e0 giudiziaria per <strong>associazione per delinquere<\/strong> (art. 416 c.p.) e <strong>truffa aggravata per il conseguimento di erogazioni pubbliche<\/strong> (art. 640-bis c.p.). Segnalati anche <strong>due soggetti giuridici<\/strong> per responsabilit\u00e0 amministrativa derivante da reato, secondo quanto previsto dal D.lgs. 231\/2001.<\/p>\n<h3>Sequestri tra Calabria e Veneto<\/h3>\n<p>Oltre ai <strong>crediti fiscali<\/strong>, \u00e8 stata eseguita un\u2019ordinanza di misure cautelari reali per equivalente sul profitto illecito, pari a 1.656.330 euro. I finanzieri hanno sequestrato disponibilit\u00e0 finanziarie, quote societarie, <strong>cinque immobili situati tra le province di Catanzaro e Venezia<\/strong> e dodici autoveicoli, tra cui una <strong>Maserati.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Operazione della Guardia di Finanza che ha smascherato un sistema di crediti d\u2019imposta fittizi legati al bonus ristrutturazioni<\/p>\n","protected":false},"author":42,"featured_media":285948,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-290053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/290053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=290053"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/290053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/285948"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=290053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=290053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=290053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}