{"id":29074,"date":"2014-01-03T06:30:37","date_gmt":"2014-01-03T05:30:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/sparano-contro-due-commercianti-di-frutta-due-arresti-nel-reggino\/"},"modified":"2023-01-17T12:45:36","modified_gmt":"2023-01-17T11:45:36","slug":"12136-sparano-contro-due-commercianti-di-frutta-due-arresti-nel-reggino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12136-sparano-contro-due-commercianti-di-frutta-due-arresti-nel-reggino\/","title":{"rendered":"Sparano contro due commercianti di frutta, due arresti nel Reggino"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; La squadra mobile di Reggio Calabria ha arrestato i due presunti responsabili del tentato omicidio di due commercianti avvenuto il 10 marzo 2012 nella citt\u00e0 dello Stretto.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Gli arresti sono stati eseguiti in esecuzione di un&#8217;ordinanza di custodia cautelare emessa dal gip su richiesta della Procura della Repubblica. I due, Antonino Pricoco, di 40 anni, e Gioele Carmelo Mangiola, di 29 anni, gi\u00e0 noti alle forze dell&#8217;ordine,&nbsp;sono accusati del tentato omicidio dei titolari di un negozio di frutta, oltre che di porto e detenzione abusiva di armi. Secondo le indagini, i due arrestati spararono contro i titolari del negozio Global frutta, Filippo Nocera e Francesco Barreca. In particolare, Pricoco e Mangiola, secondo l&#8217;accusa, il 10 marzo 2012, a bordo di una moto, si avvicinarono al negozio e spararono 11 colpi di pistola calibro 9 per 21 contro i titolari, senza per\u00f2 colpirli. Secondo le indagini il movente del tentato omicidio sarebbe stato un debito non onorato successivo all&#8217;acquisto di una moto. Le indagini, portate avanti dalla squadra mobile senza la collaborazione delle vittime, hanno permesso di accertare che il fratello di Nocera, Giuseppe, non aveva pagato alcune migliaia di euro che doveva a Pricoco per l&#8217;acquisto di una moto. A causa di ci\u00f2, secondo la ricostruzione dell&#8217;accusa, nel pomeriggio del 9 marzo, Pricoco e Mangiola aggredirono a pugni e calci Giuseppe Nocera procurandogli lesioni giudicate guaribili in 30 giorni. Il giorno successivo, i familiari di Nocera, in risposta all&#8217;aggressione, si recarono a casa di Pricoco inveendo minacciosamente alla presenza di alcune donne. Poche ore dopo, verso le 20,30, Pricoco e Mangiola, a bordo di uno scooter, si recarono al negozio &#8220;Global Frutta&#8221; gestito da Filippo Nocera e Francesco Barreca sparandogli contro undici colpi di pistola calibro 9&#215;21. I due commercianti, tuttavia, rimasero illesi per il cattivo funzionamento delle due pistole utilizzate che si incepparono pi\u00f9 volte permettendo ai due la fuga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; La squadra mobile di Reggio Calabria ha arrestato i due presunti responsabili del tentato omicidio di due commercianti avvenuto il 10 marzo 2012 nella citt\u00e0 dello Stretto.<\/p>\n","protected":false},"author":19,"featured_media":29075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-29074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29074"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29074\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29075"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}