{"id":29084,"date":"2014-01-03T08:54:20","date_gmt":"2014-01-03T07:54:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-5-gennaio-a-castrovillari-la-befana-del-poliziotto\/"},"modified":"2023-01-17T12:45:36","modified_gmt":"2023-01-17T11:45:36","slug":"12141-il-5-gennaio-a-castrovillari-la-befana-del-poliziotto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12141-il-5-gennaio-a-castrovillari-la-befana-del-poliziotto\/","title":{"rendered":"Il 5 gennaio a Castrovillari, la &#8220;Befana del poliziotto&#8221;"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Il SIULP di Castrovillari e Frascineto, giorno 5 gennaio 2014 ore 16,30, al Teatro Sybaris del Protoconvento Francescano di Castrovillari, presenter\u00e0 l&#8217;VIII edizione della Befana del Poliziotto.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Nel corso dell&#8217;evento verr\u00e0 presentata l&#8217;autobiografia di<strong> Giusy Versace<\/strong> &#8220;Con la testa e con il cuore si va ovunque&#8221; edita da Mondadori, a testimonianza di come un evento tragico di vita, quale un grave incidente stradale possa rimettere tutto in gioco, senza per questo significare un motivo di resa&#8221;. Ospiti dell&#8217;evento saranno il Segretario nazionale SIULP Felice Romano, il Vescovo di Cassano allo Ionio Monsignor Nunzio Galantino, il Prefetto di Cosenza, il Questore di Cosenza, il Dirigente Superiore della Polizia di Stato dottor Cosimo Maruccia, Giusy Versace e il dottor Pasquale Gagliardi, primario 118 che le presto&#8217; i primi soccorsi, protagonisti di un dibattito inerente la sicurezza stradale.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel corso della manifestazione saranno consegnate n. 9 borse di studio relative al II concorso pratico-artistico-letterario &#8220;Sicurezza e legalita&#8217; nell&#8217;area del Pollino&#8221;, destinate agli allievi delle scuole elementari, medie e superiori dell&#8217;area del Pollino, concorso dedicato quest&#8217;anno all&#8217;Assistente della Polizia di Stato <strong>Massimo Impieri<\/strong>, deceduto in un servizio di vigilanza stradale sulla Crotone-Cosenza e, in ricordo del quale il papa&#8217; Antonio Impieri consegnera&#8217; le borse di studio ai vincitori. A conclusione della serata verra&#8217; presentato lo show dei DuexDuo. Il ricavato della manifestazione sar\u00e0 devoluto in favore del Reparto di Pediatria dell&#8217;Ospedale Ferrari di Castrovillari e dell&#8217;Associazione Famiglie Disabili di Castrovillari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Il SIULP di Castrovillari e Frascineto, giorno 5 gennaio 2014 ore 16,30, al Teatro Sybaris del Protoconvento Francescano di Castrovillari, presenter\u00e0 l&#8217;VIII edizione della Befana del Poliziotto.<\/p>\n","protected":false},"author":19,"featured_media":29085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-29084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29084"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29085"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}