{"id":290893,"date":"2026-04-25T14:22:52","date_gmt":"2026-04-25T12:22:52","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=290893"},"modified":"2026-04-25T14:26:33","modified_gmt":"2026-04-25T12:26:33","slug":"terremoto-cosentino-magnitudo-3-7-mar-tirreno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/terremoto-cosentino-magnitudo-3-7-mar-tirreno\/","title":{"rendered":"Scossa di terremoto nel Cosentino: magnitudo 3.7 con epicentro nel Mar Tirreno"},"content":{"rendered":"<p>COSENZA &#8211; La <a href=\"https:\/\/quicosenza.it\/news\/due-scosse-di-terremoto-calabria-magnitudo-2-5\/\" target=\"_blank\" rel=\"noopener\">terra torna a tremare in Calabria.<\/a> Un <strong>terremoto di magnitudo 3.7<\/strong> \u00e8 avvenuto alle 13.43 nel <strong>Cosentino<\/strong>, precisamente nel Mar Tirreno lungo la costa della Calabra nord occidentale, al largo di Paola.<\/p>\n<h3>Terremoto nel Tirreno Cosentino, profondit\u00e0 e coordinate<\/h3>\n<p>Il <strong>sisma si \u00e8 verificato in mare ad una profondit\u00e0 di 272 km,<\/strong> dunque non \u00e8 stato avvertito dalla popolazione e non ha causato danni a persone o cose. Le coordinate geografiche (lat, lon) sono 39.2882, 15.7760.\u00a0Il terremoto \u00e8 stato localizzato dalla Sala Sismica INGV-Roma.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-290894\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Terremoto_largo-Paola.jpg\" alt=\"terremoto cosentino Tirreno \" width=\"498\" height=\"320\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Terremoto_largo-Paola.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Terremoto_largo-Paola-300x193.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Terremoto_largo-Paola-768x493.jpg 768w\" sizes=\"auto, (max-width: 498px) 100vw, 498px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sisma \u00e8 avvenuto in mare ad una profondit\u00e0 di 272 km, al largo di Paola, motivo per il quale non ha causato danni a persone o cose<\/p>\n","protected":false},"author":90,"featured_media":268148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[],"class_list":["post-290893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/290893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=290893"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/290893\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/268148"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=290893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=290893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=290893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}