{"id":290918,"date":"2026-04-26T08:24:12","date_gmt":"2026-04-26T06:24:12","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=290918"},"modified":"2026-04-26T08:26:36","modified_gmt":"2026-04-26T06:26:36","slug":"ecobus-attivo-oggi-servizio-mobile-rifiuti-siba","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ecobus-attivo-oggi-servizio-mobile-rifiuti-siba\/","title":{"rendered":"EcoBus attivo da oggi: servizio mobile a Marina di Sibari per conferire rifiuti differenziati"},"content":{"rendered":"<p>CASSANO IONIO (CS) &#8211; Il <a href=\"https:\/\/www.facebook.com\/ComunediCassanolonio\" rel=\"noopener\">Comune<\/a> di Cassano all&#8217;Ionio informa la cittadinanza che, a partire da oggi, domenica 26 aprile, sar\u00e0 attivato a <strong>Marina di Sibari il servizio EcoBus,<\/strong> un nuovo <strong>punto mobile<\/strong> dedicato al conferimento dei <strong>rifiuti differenziati<\/strong>. Si tratta di una soluzione temporanea pensata per garantire la continuit\u00e0 della raccolta in una fase di transizione, assicurando ai cittadini la possibilit\u00e0 di smaltire correttamente i rifiuti.<\/p>\n<h3>Servizio EcoBus per i rifiuti, come funziona<\/h3>\n<p>Gli EcoBus sono dotati di <strong>compattatori per plastica, umido, vetro e indifferenziato<\/strong>. Il servizio \u00e8 stato attivato dall\u2019Amministrazione comunale in collaborazione con Progitec. Il mezzo stazioner\u00e0 davanti <strong>all\u2019Area K<\/strong> e sar\u00e0 operativo dalle <strong>ore 17:00 alle ore 21:00<\/strong> nelle seguenti date:<\/p>\n<p><strong>&#8211; 26 aprile<\/strong><br \/>\n<strong>&#8211; 2 e 3 maggio<\/strong><br \/>\n<strong>&#8211; 9 e 10 maggio<\/strong><br \/>\n<strong>&#8211; 16 e 17 maggio<\/strong><br \/>\n<strong>&#8211; 23 e 24 maggio<\/strong><br \/>\n<strong>&#8211; 30 e 31 maggio<\/strong><br \/>\n<strong>&#8211; 2 giugno<\/strong><\/p>\n<h3>Una misura temporanea di upporto ai cittadini: l&#8217; invito alla collaborazione<\/h3>\n<p>L\u2019attivazione degli EcoBus era stata gi\u00e0 anticipata durante un <strong>incontro tra l\u2019Amministrazione comunale e l\u2019associazione dei commercianti \u201cMarina di Sibari<\/strong>\u201d. Il servizio rappresenta infatti una <strong>misura sostitutiva temporanea<\/strong>. L\u2019Area K \u00e8 attualmente chiusa per consentire i lavori di realizzazione dei <strong>Centri Comunali di Raccolta<\/strong> (CCR), intervento che ha <strong>subito rallentamenti<\/strong> anche a causa dei <strong>sette cicloni che, tra met\u00e0 gennaio e fine marzo, hanno interessato il territorio<\/strong>.<\/p>\n<p>Nonostante la fase transitoria, il servizio EcoBus permetter\u00e0 a residenti e cittadini di <strong>continuare a conferire correttamente i rifiuti<\/strong>, contribuendo al mantenimento del decoro urbano e al rispetto dell\u2019ambiente. A supporto della cittadinanza sar\u00e0 presente personale della Progitec, pronto a fornire indicazioni e assistenza per il corretto utilizzo del servizio. L\u2019Amministrazione comunale invita tutti alla massima collaborazione, <strong>rispettando gli orari indicati e le modalit\u00e0 previste per la raccolta differenziata<\/strong>, al fine di garantire un servizio efficace e condiviso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-290921\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Ecobus-Cassano-AllIonio-rifiuti-differenziati-02.jpg\" alt=\"Ecobus Cassano All&#039;Ionio rifiuti differenziati 02\" width=\"607\" height=\"911\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Ecobus-Cassano-AllIonio-rifiuti-differenziati-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Ecobus-Cassano-AllIonio-rifiuti-differenziati-02-200x300.jpg 200w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Ecobus-Cassano-AllIonio-rifiuti-differenziati-02-683x1024.jpg 683w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Ecobus-Cassano-AllIonio-rifiuti-differenziati-02-768x1152.jpg 768w\" sizes=\"auto, (max-width: 607px) 100vw, 607px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Cassano all\u2019Ionio ha avviato a partire da oggi, un servizio mobile per il conferimento dei rifiuti durante la chiusura temporanea dell\u2019Area K<\/p>\n","protected":false},"author":42,"featured_media":290919,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[],"class_list":["post-290918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/290918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=290918"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/290918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/290919"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=290918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=290918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=290918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}