{"id":291282,"date":"2026-04-30T06:57:31","date_gmt":"2026-04-30T04:57:31","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=291282"},"modified":"2026-05-04T08:25:46","modified_gmt":"2026-05-04T06:25:46","slug":"roberto-occhiuto-circolo-pd-di-cosenza-frantumi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/roberto-occhiuto-circolo-pd-di-cosenza-frantumi\/","title":{"rendered":"Roberto Occhiuto &#8220;padrone di casa&#8221; nel circolo cittadino: il PD di Cosenza in frantumi"},"content":{"rendered":"<p>COSENZA &#8211; Se il circolo cittadino del Partito Democratico di Cosenza voleva rimarcare <strong>la distanza dalla maggioranza<\/strong> del partito e lanciare un <strong>nuovo messaggio a Franz Caruso<\/strong>, con \u201c<strong><em>l\u2019imbarazzante\u201d<\/em><\/strong> <a href=\"https:\/\/quicosenza.it\/news\/occhiuto-appalto-entro-giugno-lavori-fine-anno\/\">incontro<\/a> sulla realizzazione del nuovo ospedale di Cosenza, pu\u00f2 dirsi riuscito nell\u2019intento.<\/p>\n<p>Non prendendo le distanze sul luogo della costruzione del nuovo Ospedale Hub di Cosenza, infatti, si \u00e8 ulteriormente accentuata la linea di demarcazione rispetto ai <strong>nove consiglieri comunali<\/strong>, al <strong>presidente del Consiglio comunale<\/strong>, <strong>all\u2019assessore Damiano Covelli<\/strong>, al vicesindaco <strong>Maria Locanto<\/strong> e alla stessa <strong>segreteria provinciale del partito.\u00a0<\/strong>Una spaccatura che trova il presidente nazionale del PSI Luigi Incaranto (presente anche lui all\u2019incontro del <a href=\"https:\/\/www.facebook.com\/circolopdcosenza\" target=\"_blank\" rel=\"noopener\">circolo<\/a> &#8220;Marica Zuccarelli&#8221;), un prezioso alleato, determinatasi com\u2019\u00e8 ormai risaputo, dopo le ultime elezioni regionali.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-291274 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Nuovo-Ospedale-hub-di-Cosenza.jpg\" alt=\"Nuovo Ospedale hub di Cosenza\" width=\"654\" height=\"407\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Nuovo-Ospedale-hub-di-Cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Nuovo-Ospedale-hub-di-Cosenza-300x187.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Nuovo-Ospedale-hub-di-Cosenza-768x478.jpg 768w\" sizes=\"auto, (max-width: 654px) 100vw, 654px\" \/><\/p>\n<h3>La rottura insanabile nel Pd di Cosenza<\/h3>\n<p>Imbarazzante perch\u00e9 \u00e8 stato sotto gli occhi, lo \u201c<strong>sbertucciamento\u201d del presidente della Regione Calabria, Roberto Occhiuto da ospite in \u201ccasa del Pd\u201d.<\/strong> A sorpresa, infatti, il presidente ha annunciato <strong>la disponibilit\u00e0 dei fondi per la realizzazione del nuovo ospedale a Rende<\/strong>, assicurando l\u2019avvio dei lavori entro l\u2019anno. Un annuncio che non ha convinto del tutto <a href=\"https:\/\/quicosenza.it\/news\/nuovo-ospedale-cosenza-de-salazar-guccione\/\" target=\"_blank\" rel=\"noopener\">Carlo Guccione,<\/a> il quale ha sottolineato come l\u2019intervento non possa ridursi a una mera operazione di <strong>edilizia sanitaria<\/strong>, ma debba configurarsi come una vera riforma del sistema ospedaliero su scala provinciale e regionale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-291285\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Incontro-ospedale-circolo-PD-di-Cosenza.jpg\" alt=\"Incontro sanit\u00e0 e ospedale PD di Cosenza\" width=\"657\" height=\"408\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Incontro-ospedale-circolo-PD-di-Cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Incontro-ospedale-circolo-PD-di-Cosenza-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/Incontro-ospedale-circolo-PD-di-Cosenza-768x477.jpg 768w\" sizes=\"auto, (max-width: 657px) 100vw, 657px\" \/><\/p>\n<p>Da qui la necessit\u00e0 di istituire <strong>un\u2019azienda ospedaliera universitaria<\/strong>, capace di integrare la facolt\u00e0 di medicina, il nuovo hub e la rete degli ospedali spoke del territorio. Una visione che, ad ogni modo, si inserisce per\u00f2 in un contesto politico segnato da <strong>divisioni profonde<\/strong>.\u00a0E infatti, al di l\u00e0 delle posizioni nel merito, il dato politico resta: il progetto <strong>\u201cObiettivo Cosenza 2050<\/strong>\u201d, promosso da una componente minoritaria del partito cittadino, testimonia l<strong>a frattura interna al PD<\/strong>. Una litigiosit\u00e0 che dovrebbe far riflettere, soprattutto in vista di una scadenza tutt\u2019altro che lontana; tra un anno i cittadini saranno chiamati alle urne per eleggere il nuovo sindaco di Cosenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019incontro del circolo &#8216;Zuccarelli&#8217; certifica la rottura con la segreteria provinciale. La sfida sulla sanit\u00e0 diventa il terreno di scontro elettorale e rafforza l\u2019asse inedito tra il PSI di Incarnato e la minoranza PD<\/p>\n","protected":false},"author":66,"featured_media":291283,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-291282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/291282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=291282"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/291282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/291283"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=291282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=291282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=291282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}