{"id":291544,"date":"2026-05-03T17:20:41","date_gmt":"2026-05-03T15:20:41","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=291544"},"modified":"2026-05-03T18:01:56","modified_gmt":"2026-05-03T16:01:56","slug":"vandalizzata-auto-sindaco-san-ferdinando","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/vandalizzata-auto-sindaco-san-ferdinando\/","title":{"rendered":"Vandalizzata l&#8217;auto del sindaco di San Ferdinando \u00abgrazie per questa gentile espressione di dissenso\u00bb"},"content":{"rendered":"<p>SAN FERDINANDO (RC) &#8211; Il sindaco di San Ferdinando, <strong>Gianluca Gaetano<\/strong>, ha denunciato il danneggiamento della propria auto, graffiata nella parte anteriore del cofano. La foto della vettura e poche parole affidate ai social: <em>\u201cGrazie di cuore per questa gentile, sommessa, eterea, quasi impalpabile espressione di dissenso\u201d. <\/em>Un gesto vandalico compiuto da ignoti che lo stesso primo cittadino riconduce a una forma di dissenso, lasciando intendere una possibile matrice intimidatoria. Non \u00e8 per\u00f2 chiaro, al momento, a quale ambito o situazione specifica possa essere collegato l\u2019episodio.<\/p>\n<h3>La solidariet\u00e0 al sindaco di San Ferdinando<\/h3>\n<p>La denuncia pubblica ha subito suscitato una <strong>vasta ondata di solidariet\u00e0 da parte di cittadini, amici e sostenitori<\/strong>, che hanno espresso vicinanza e condanna per l\u2019accaduto. Tra i tanti messaggi, c\u2019\u00e8 chi scrive: \u201cpiena solidariet\u00e0 Sindaco. Spero che i destinatari dei tuoi generosi versi vengano presi e vedano il sole a scacchi per il tempo che basta a riflettere sul dissenso e sul senso civico in generale\u201d. E ancora: \u201cPurtroppo abbiamo ancora tanto da lavorare, questi soggetti non conoscono il dialogo e purtroppo questo \u00e8 l&#8217;unico modo che conoscono per esprimersi, mi dispiace tanto\u201d.<\/p>\n<h3>\u201cIl dissenso non \u00e8 vandalismo\u201d<\/h3>\n<p>Molti interventi sotto il post del sindaco sottolineano come il <strong>dissenso<\/strong> debba essere <strong>espresso in modo civile e diretto<\/strong>: \u201cIl dissenso si manifesta faccia a faccia, questa \u00e8 solamente vigliaccheria\u201d. \u201cIl vandalismo \u00e8 l&#8217;unico linguaggio di chi non ha argomenti, n\u00e9 il coraggio di sostenere le proprie idee a viso aperto\u201d. \u201cQuello che resta racconta solo povert\u00e0 di idee, di confronto e di visione per un luogo e una comunit\u00e0\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Danneggiata la vettura del primo cittadino di San Ferdinando. Il post ironico sui social e la comunit\u00e0 compatta nel sostegno<\/p>\n","protected":false},"author":42,"featured_media":291545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-291544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/291544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=291544"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/291544\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/291545"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=291544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=291544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=291544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}