{"id":291714,"date":"2026-05-05T13:00:31","date_gmt":"2026-05-05T11:00:31","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=291714"},"modified":"2026-05-05T12:12:24","modified_gmt":"2026-05-05T10:12:24","slug":"strage-gatti-avvelenati-scatta-denuncia-gaia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/strage-gatti-avvelenati-scatta-denuncia-gaia\/","title":{"rendered":"Strage in strada, ritrovati diversi gatti avvelenati. Scatta la denuncia di Gaia: \u00abChiediamo di indagare\u00bb"},"content":{"rendered":"<p>SPILINGA (VV) &#8211; <strong>Gatti avvelenati<\/strong> ritrovati senza vita ed in condizioni terribili in strada. \u00c8 quello che \u00e8 successo a fine aprile in Via Primo Maggio, a Spilinga e che denuncia<a href=\"https:\/\/gaiaitalia.it\/home\/\" target=\"_blank\" rel=\"noopener\"> l&#8217;associazione Gaia Animali &amp; Ambiente.<\/a> Si trattava di una colonia che veniva curata e nutrita da una residente del luogo, una prassi che qualcuno ha deciso di fermare.<\/p>\n<h3>Gatti avvelenati, la denuncia di Gaia Animali &amp; Ambiente<\/h3>\n<p>Di fronte ad un gesto crudele e che non pu\u00f2 essere ignorato, che purtroppo si ripete <a href=\"https:\/\/quicosenza.it\/news\/a-cosenza-gatti-morti-in-via-dei-mille-le-associazioni-lanciano-lallarme-giustizia-e-tutela-per-i-mici\/\" target=\"_blank\" rel=\"noopener\">anche in altre citt\u00e0<\/a>, l&#8217;associazione Gaia Animali &amp; Ambiente ha presentato denuncia alla Procura della Repubblica presso il Tribunale di Vibo Valentia, tramite dall&#8217;avvocato Eleonora Carchedi di Gaia Lex Vibo Valentia.<\/p>\n<p>Sui gatti avvelenati il presidente nazionale di Gaia Animali &amp; Ambiente, <strong>Edgar Meyer<\/strong> dice:\u00a0&#8220;<strong>Chiediamo di indagare. <\/strong>Paiono ravvisarsi profili di responsabilit\u00e0 penale. Ho firmato denuncia-querela nei confronti di chiunque venga ritenuto responsabile per il reato di uccisione di animali ex art. 544 bis C.P. e per ogni altra contestazione, <strong>chiedendone la punizione<\/strong> ai sensi di legge per tutti i reati. L&#8217;avvelenamento di animali \u00e8 un reato punito dal Codice Penale&#8221;, conclude Meyer.<\/p>\n<h3>&#8220;Crimine da non sottovalutare&#8221;<\/h3>\n<p>&#8220;Ricordiamo che la Legge \u00e8 severa, e spero si possa fare luce su quanto accaduto, affinch\u00e9 il responsabile non rimanga impunito &#8211; afferma l&#8217;avvocato Carchedi &#8211; Si tratta di un <strong>crimine che non pu\u00f2 essere sottovalutato,<\/strong> in quanto episodi di questo genere non possono che rappresentare un segnale di pericolosit\u00e0 sociale. Chi fa del male a chi non pu\u00f2 difendersi, ferisce tutti noi. \u00c8 &#8211; conclude l&#8217;avv. Carchedi &#8211; una comunit\u00e0 che si volta dall&#8217;altra parte, smette, poco alla volta, di essere una comunit\u00e0&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente Edgar Meyer: &#8220;Paiono ravvisarsi profili di responsabilit\u00e0 penale. Ho firmato denuncia-querela nei confronti di chiunque venga ritenuto responsabile per il reato di uccisione di animali&#8221; <\/p>\n","protected":false},"author":90,"featured_media":291715,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-291714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/291714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=291714"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/291714\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/291715"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=291714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=291714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=291714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}