{"id":291843,"date":"2026-05-06T16:00:16","date_gmt":"2026-05-06T14:00:16","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=291843"},"modified":"2026-05-06T15:37:18","modified_gmt":"2026-05-06T13:37:18","slug":"cosenza-studenti-riscopron-radici-scuola-lavoro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-studenti-riscopron-radici-scuola-lavoro\/","title":{"rendered":"Cosenza, gli studenti riscoprono le proprie radici: al via le giornate conclusive del progetto Scuola-Lavoro"},"content":{"rendered":"<p>COSENZA &#8211; \u00c8 in dirittura d&#8217;arrivo la prima edizione del progetto di formazione <a href=\"https:\/\/quicosenza.it\/news\/cosenza-giovani-storici-progetto-scuola-lavoro\/\" target=\"_blank\" rel=\"noopener\">Scuola-Lavoro<\/a> sulla storia del territorio di Cosenza, promosso dall&#8217;amministrazione comunale e che ha coinvolto alcuni istituti scolastici della citt\u00e0 con il dichiarato obiettivo di promuovere la conoscenza del patrimonio storico e culturale della citt\u00e0.<\/p>\n<h3>Cosenza, parte la prima giornata conclusiva del progetto Scuola-Lavoro<\/h3>\n<p>Le manifestazioni in programma il prossimo 20 maggio segnano la conclusione di alcuni dei moduli di ricerca nei quali il progetto si \u00e8 articolato. Alle 9,30 il Cinema Italia-Tieri ospiter\u00e0 la manifestazione conclusiva dei moduli che hanno visto coinvolto <strong>l&#8217;Istituto professionale per i Servizi Sociali &#8220;Da Vinci-Nitti&#8221;<\/strong>: &#8220;Costume e tradizioni religiose del territorio cosentino&#8221;, &#8220;Enogastronomia del territorio cosentino&#8221;; &#8220;Teatro e Cinema del territorio cosentino&#8221;.<\/p>\n<p>Nel pomeriggio nell&#8217;aula magna del <strong>Liceo Scientifico &#8220;Scorza&#8221;,<\/strong> \u00e8 prevista, invece, alle ore 16,00, la manifestazione di chiusura dei tre moduli di ricerca su cui si sono impegnati gli studenti dello &#8220;Scorza&#8221;: &#8220;letteratura, poesia, anche in vernacolo, del territorio cosentino&#8221; e &#8220;citt\u00e0 e suoi personaggi pi\u00f9 rappresentativi, dalle origini fino ai nostri giorni&#8221;.<\/p>\n<p>Alla manifestazione del mattino, al Cinema-Italia Tieri, parteciperanno il sindaco <a href=\"https:\/\/www.facebook.com\/franzcaruso\" target=\"_blank\" rel=\"noopener\"><strong>Franz Caruso<\/strong>,<\/a> il consigliere delegato all&#8217;istruzione <strong>Aldo Trecroci,<\/strong> che ha ispirato l&#8217;intero progetto, il dirigente scolastico dell&#8217;Istituto di Istruzione Superiore &#8220;Da Vinci Nitti&#8221;, <strong>Damiano De Paola,<\/strong> la docente universitaria <strong>Maria Rosaria Salerno,<\/strong> coordinatrice tecnica del progetto di formazione Scuola-Lavoro e rappresentante del Dipartimento scienze umanistiche dell&#8217;Unical che ha siglato con il Comune un protocollo d&#8217;intesa, gli esperti\/tutor esterni, prof. <strong>Carlo Fanelli,<\/strong> il direttore del museo diocesano don Salvatore Fuscaldo, il prof. <strong>Eugenio De Rose<\/strong> e l&#8217;ing. <strong>Emilio Iantorno<\/strong> oltre ai tutor interni prof.sse <strong>Patrizia Murano, Carmela Visalli Melina<\/strong> e i prof. <strong>Guerino Avolio e Tullio Cerzoso.<\/strong><\/p>\n<p>Alla manifestazione del pomeriggio parteciperanno, invece, la dirigente scolastica del liceo scientifico &#8220;G.B. Scorza&#8221;, prof.ssa <strong>Rosanna Rizzo,<\/strong> i tutor esperti esterni, prof.sse <strong>Maria Luigia Campolongo, Marilena Fera e Caterina Gammaldi,<\/strong> il prof.<strong> Alfonso Guzzo Foliaro<\/strong> e il dott. <strong>Sergio Chiatto<\/strong>, i tutor interni Prof.ssa <strong>Alfonsa Arabia<\/strong> e prof. <strong>Armando Rossi.<\/strong><\/p>\n<h3>Le parole del sindaco Caruso<\/h3>\n<p>&#8220;Cosenza \u2013 sottolinea il sindaco Franz Caruso &#8211; \u00e8 una citt\u00e0 dalla storia importante e dalle radici profonde che \u00e8 stato indispensabile far conoscere e valorizzare. I risultati auspicati ed ai quali \u00e8 pervenuto il progetto, credo vadano proprio in questa direzione. Sono convinto da sempre che <strong>non esiste futuro senza il passato.<\/strong> Questo <strong>progetto valorizza le nostre origini<\/strong> perch\u00e9 i moduli di ricerca su cui le scuole hanno lavorato hanno attraversato l&#8217;intera storia di Cosenza, analizzandone le molteplici espressioni e l&#8217;evoluzione culturale del suo territorio&#8221;.<\/p>\n<p>&#8220;Sar\u00e0 capitato a tutti di imbattersi nel nome di una strada intitolata a figure importanti domandandosi chi fossero. Interrogativi che nei nostri giovani sono ancora pi\u00f9 frequenti. Dare, con le ricerche condotte, nuovo valore, ad esempio, alla toponomastica cittadina, pu\u00f2 aver colmato questo deficit di conoscenza&#8221;.<\/p>\n<h3>Altri incontri conclusivi per presentare i lavori svolti<\/h3>\n<p>A quella del 20 maggio seguiranno <strong>altre giornate conclusive<\/strong> degli ulteriori moduli di ricerca nei quali il progetto si \u00e8 sviluppato negli istituti scolastici della citt\u00e0. &#8220;Quello che illustreremo il 20 maggio \u2013 sottolinea il delegato all&#8217;Istruzione <strong>Aldo Trecroci<\/strong> &#8211; \u00e8 un<strong> primo risultato di un&#8217;esperienza che si intende proseguire negli anni a venire,<\/strong> per completare il lavoro svolto dalle scuole&#8221;.<\/p>\n<p>Il progetto si \u00e8 articolato in 13 moduli di ricerca che hanno offerto una<strong> visione ampia e integrata dell&#8217;identit\u00e0 culturale del territorio cosentino<\/strong>. &#8220;Giova ricordare &#8211; ha aggiunto Trecroci \u2013 la collaborazione al progetto della Fondazione &#8220;Attilio ed Elena Giuliani&#8221; e della casa editrice &#8220;Luigi Pellegrini&#8221;, rappresentate da Walter Pellegrini, e quella degli esperti esterni e dei tutor interni che hanno coordinato i diversi moduli di ricerca&#8221;.<\/p>\n<p>Il progetto, che vuole anche rafforzare il sentimento di appartenenza delle nuove generazioni al territorio cosentino, \u00e8 solo all&#8217;inizio del suo percorso: \u00e8 intenzione dell&#8217;amministrazione comunale proseguire, potenziare e ampliare la ricerca storica appena iniziata. Entro la fine del mese di maggio si terranno <strong>altri incontri di presentazione dei lavori svolti<\/strong> con il Polo Brutium, il liceo classico Telesio, il liceo scientifico paritario &#8220;R. Misasi&#8221;, riguardanti gli altri otto moduli nei quali \u00e8 articolato il progetto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco Franz Caruso e il delegato Aldo Trecroci presentano i risultati dei primi moduli di ricerca: un viaggio tra banchi di scuola e storia della propria citt\u00e0. Appuntamento al 20 maggio<\/p>\n","protected":false},"author":90,"featured_media":291845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-291843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/291843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=291843"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/291843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/291845"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=291843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=291843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=291843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}