{"id":29201,"date":"2014-01-07T09:46:38","date_gmt":"2014-01-07T08:46:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/paura-nella-notte-a-pizzo-per-un-incendio-in-un-condominio\/"},"modified":"2023-01-17T12:45:42","modified_gmt":"2023-01-17T11:45:42","slug":"12201-paura-nella-notte-a-pizzo-per-un-incendio-in-un-condominio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12201-paura-nella-notte-a-pizzo-per-un-incendio-in-un-condominio\/","title":{"rendered":"Paura nella notte a Pizzo per un incendio in un condominio"},"content":{"rendered":"<p>PIZZO CALABRO &#8211; Momenti di panico nella notte in un condominio di Pizzo Calabro nel Vibonese.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un incendio si \u00e8 sviluppato durante la notte in un appartamento in contrada Sant&#8217;Antonio, nel condominio Miramare. Sul posto sono intervenute tre squadre dei Vigili del Fuoco, che hanno iniziato l&#8217;opera di spegnimento e a scopo precauzionale, hanno fatto evacuare l&#8217;intero stabile, circa quaranta persone. L&#8217;abitazione in cui si sono sviluppate le fiamme, in quel momento, non era abitata ma tutte le suppellettili dell&#8217;appartamento sono state distrutte o danneggiate dal fuoco. I Vigili del fuoco, terminate le operazioni intorno alle 3.45, hanno poi fatto rientrare nelle loro abitazioni tutti gli occupanti dello stabile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PIZZO CALABRO &#8211; Momenti di panico nella notte in un condominio di Pizzo Calabro nel Vibonese.<\/p>\n","protected":false},"author":19,"featured_media":29202,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-29201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29201"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29202"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}