{"id":29207,"date":"2014-01-07T15:09:44","date_gmt":"2014-01-07T14:09:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/gioco-d-azzardo-sindaco-piane-crati-sottoscrive-petizione-dell-idv\/"},"modified":"2023-01-17T12:45:42","modified_gmt":"2023-01-17T11:45:42","slug":"12204-gioco-d-azzardo-sindaco-piane-crati-sottoscrive-petizione-dell-idv","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12204-gioco-d-azzardo-sindaco-piane-crati-sottoscrive-petizione-dell-idv\/","title":{"rendered":"Gioco d&#8217;azzardo: sindaco Piane Crati sottoscrive petizione dell&#8217;Idv"},"content":{"rendered":"<p>PIANE CRATI (CS) &#8211; &#8220;Quando le idee sono comuni, anche le volonta&#8217; si incontrano&#8221;.<\/p>\n<p>  <!--more-->  <\/p>\n<p>E&#8217; il commento di Daniela Caprino, consigliere comunale di Aprigliano di Italia dei Valori, al fatto che il sindaco del Pd di Piane Crati, Silvano Sacchetta, ha sottoscritto il progetto di legge del suo partito contro il gioco d&#8217;azzardo. &#8220;Quest&#8217;ultimo &#8211; si legge in una nota -, sollecitato dalla stessa Caprino sta portando avanti la battaglia contro il gioco d&#8217;azzardo, non ha esitato a dar ela su adesione a sostegno dell&#8217;iniziativa. Cio&#8217; dimostra che il colore politico e l&#8217;appartenenza a partiti diversi possono essere facilmente superati quando al centro dell&#8217;azione politica c&#8217;e&#8217; l&#8217;interesse per i cittadini. E il gioco d&#8217;azzardo e&#8217; un fenomeno che interessa e coinvolge indistintamente intere famiglie, giovani e pensionati che ogni giorno spendono centinaia e migliaia di euro alla ricerca di un facile arricchimento che, spesso, li riduce alla poverta&#8217; assoluta. Tutelare queste persone &#8211; conclude &#8211; significa riconoscere che, anche se provenienti da schieramenti diversi, ci si puo&#8217; incontrare e impegnarsi in una battaglia che riguarda l&#8217;esclusivo interesse dei cittadini&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PIANE CRATI (CS) &#8211; &#8220;Quando le idee sono comuni, anche le volonta&#8217; si incontrano&#8221;.<\/p>\n","protected":false},"author":22,"featured_media":29208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-29207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29207"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29208"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}