{"id":29233,"date":"2014-01-08T09:36:52","date_gmt":"2014-01-08T08:36:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/pietrapaola-e-giallo-sulla-morte-dell-anziano-guerino-calio\/"},"modified":"2023-01-17T12:45:44","modified_gmt":"2023-01-17T11:45:44","slug":"12217-pietrapaola-e-giallo-sulla-morte-dell-anziano-guerino-calio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12217-pietrapaola-e-giallo-sulla-morte-dell-anziano-guerino-calio\/","title":{"rendered":"Pietrapaola, \u00e8 giallo sulla morte dell&#8217;anziano Guerino Cali\u00f2"},"content":{"rendered":"<p>PIETRAPAOLA (CS) &#8211; Si attende l\u2019esito dell\u2019autopsia per chiarire come sia morto Guerino Cali\u00f2.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il pensionato di 78 anni, di Pietrapaola, in provincia di Cosenza, era sparito il 13 dicembre scorso dopo aver ritirato la pensione alle Poste ed era stato trovato cadavere 18 giorni dopo, in fondo ad una scarpata. Secondo gli inquirenti infatti, che mantengono il massimo riserbo sulla vicenda, potrebbe anche trattarsi di omicidio. Per questo gli uomini del Ris, sono tornati sul luogo del ritrovamento ma anche nell\u2019abitazione dell\u2019uomo per cercare di capire cosa sia accaduto al 78enne, che \u00e8 stato ritrovato senza soldi in tasca, nonostante fosse andato a ritirare la pensione, e secondo quanto raccontato dai conoscenti, non usciva mai senza un euro in tasca. Inoltre pare che Cali\u00f2, sempre secondo il racconto delle persone che lo conoscevano bene, era solito indossare in qualsiasi stagione uno dei suoi cappelli a borsalino e si accompagnava sempre da un bastone. Ma quando \u00e8 stato trovato in fondo alla scarpata, burrone non aveva n\u00e9 l\u2019uno n\u00e9 l\u2019altro. Ma ci sarebbero altri dubbi sui quali gli inquirenti stanno lavorando; uno di questi \u00e8 legato a diverse fratture che potrebbero non essere legate alla caduta nel burrone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PIETRAPAOLA (CS) &#8211; Si attende l\u2019esito dell\u2019autopsia per chiarire come sia morto Guerino Cali\u00f2.<\/p>\n","protected":false},"author":19,"featured_media":29234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-29233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29233"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29234"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}