{"id":29289,"date":"2014-01-09T14:54:43","date_gmt":"2014-01-09T13:54:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/joppolo-incendiata-una-villetta-sul-lungomare\/"},"modified":"2023-01-17T12:45:48","modified_gmt":"2023-01-17T11:45:48","slug":"12245-joppolo-incendiata-una-villetta-sul-lungomare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12245-joppolo-incendiata-una-villetta-sul-lungomare\/","title":{"rendered":"Joppolo, incendiata una villetta sul lungomare"},"content":{"rendered":"<p>JOPPOLO (VV) &#8211; Un incendio ha danneggiato una villetta sul lungomare di Joppolo, nel Vibonese, di propriet\u00e0 di una insegnante, A.P., di 51 anni.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Ad accorgersi dei danni, che sono ancora in corso di quantificazione, provocati dalle fiamme \u00e8 stata la stessa donna che ha allertato i Carabinieri. I militari accorsi sul posto non hanno trovato al momento, elementi utili per accertare le cause dell&#8217;incendio risalente a qualche giorno addietro. Si segue comunque la pista della probabile origine dolosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>JOPPOLO (VV) &#8211; Un incendio ha danneggiato una villetta sul lungomare di Joppolo, nel Vibonese, di propriet\u00e0 di una insegnante, A.P., di 51 anni.<\/p>\n","protected":false},"author":22,"featured_media":29290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-29289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29289"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29290"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}