{"id":29291,"date":"2014-01-09T15:04:49","date_gmt":"2014-01-09T14:04:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/giovanissimi-danneggiano-la-scuola-per-evitare-le-lezioni\/"},"modified":"2023-01-17T12:45:48","modified_gmt":"2023-01-17T11:45:48","slug":"12246-giovanissimi-danneggiano-la-scuola-per-evitare-le-lezioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12246-giovanissimi-danneggiano-la-scuola-per-evitare-le-lezioni\/","title":{"rendered":"Giovanissimi danneggiano la scuola per evitare le lezioni"},"content":{"rendered":"<p>ISOLA CAPO RIZZUTO (KR) &#8211; Due studenti sono stati denunciati per aver danneggiato la scuola al fine di evitare le lezioni.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Sono stati scoperti e denunciati dai Carabinieri due studenti minorenni, di 14 e 15 anni, che insieme ad un terzo ragazzo, non imputabile poich\u00e8 12enne, erano entrati clandestinamente in due distinte scuole di Isola di Capo Rizzuto (Kr) imbrattando i pavimenti con della vernice. I due sono stati segnalati alla Procura dei minorenni di Catanzaro. I Carabinieri, erano intervenuti alle 23 circa di ieri sera, dopo avere appreso che alcuni ragazzi, poco prima, si erano resi protagonisti di atti vandalici in due scuole, precisamente all&#8217;interno della scuola &#8220;Karol Wojtyla&#8221; in via Libert\u00e0, e all&#8217;interno della scuola media &#8220;G. da Fiore&#8221; in via Madonna degli Angeli.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel primo caso, i ragazzi, dopo aver infranto il vetro della porta di ingresso principale, si sarebbero introdotti all&#8217;interno dei locali ed avrebbero cosparso il pavimento e le mura dell&#8217;androne di ingresso di vernice di colore rosso, imbrattando anche diversi arredi presenti. Nella scuola Da Fiore, invece,dopo aver infranto il vetro della porta sul retro dell&#8217;edificio, data l&#8217;impossibilit\u00e0 ad accedere all&#8217;interno, avrebbero imbrattato la porta stessa. Nel cortile i militari hanno rinvenuto un secchio di plastica contenente vernice di colore rosso, utilizzato dai vandali per compiere entrambi i danneggiamenti. I Carabinieri sono riusciti ad individuare gli autori di entrambi i danneggiamenti e presentatisi nelle loro abitazioni, a seguito di un&#8217;ispezione domiciliare, hanno recuperato gli abiti ancora macchiati dalla vernice utilizzata, successivamente posti sotto sequestro. Dei tre, il 14enne ed il 15enne risultano frequentare la scuola media presa d&#8217;assalto. Questo episodio segue quello accaduto il 19 febbraio 2013 in cui 8 minori cercarono di appiccare il fuoco alla stessa scuola media &#8220;da Fiore&#8221;. Anche in quel caso i Carabinieri riuscirono ad intervenire assicurando alla giustizia i piccoli vandali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ISOLA CAPO RIZZUTO (KR) &#8211; Due studenti sono stati denunciati per aver danneggiato la scuola al fine di evitare le lezioni.<\/p>\n","protected":false},"author":22,"featured_media":29292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-29291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29291"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29292"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}