{"id":293568,"date":"2026-05-25T08:45:47","date_gmt":"2026-05-25T06:45:47","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=293568"},"modified":"2026-05-25T08:51:42","modified_gmt":"2026-05-25T06:51:42","slug":"carcere-arghilla-distrutti-presidi-telemedicina","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/carcere-arghilla-distrutti-presidi-telemedicina\/","title":{"rendered":"Caos nel carcere di Arghill\u00e0: distrutti i presidi di telemedicina \u00aba rischio il diritto alle cure dei detenuti\u00bb"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Apparecchiature tecniche e tecnologiche destinate alla telemedicina e all\u2019assistenza sanitaria delle persone detenute distrutte: \u201cun fatto di eccezionale gravit\u00e0 istituzionale, umana e civile\u201d. E&#8217; quanto accaduto nelle ultime ore <strong>all\u2019interno della Casa Circondariale di <a href=\"https:\/\/www.giustizia.it\/giustizia\/it\/dettaglio_scheda.page?s=MII179988\" rel=\"noopener\">Arghill\u00e0<\/a><\/strong> e, a lanciare l\u2019allarme, \u00e8 il <strong>Garante regionale Russo<\/strong>, che esprime forte preoccupazione per le conseguenze dell\u2019accaduto sul diritto alla salute dei detenuti e sulle condizioni operative del personale sanitario e penitenziario.<\/p>\n<h3>Apparecchiature Telemedicina danneggiate: \u201cattacco diretto al diritto alla salute\u201d<\/h3>\n<p>Secondo il Garante, il danneggiamento delle apparecchiature non rappresenta soltanto un <strong>episodio vandalico<\/strong>, ma \u201cun attacco diretto alla possibilit\u00e0 di garantire cure, assistenza, dignit\u00e0 e tutela della salute all\u2019interno di un istituto penitenziario gi\u00e0 profondamente segnato da criticit\u00e0 strutturali, organizzative e di sicurezza\u201d.\u00a0Russo sottolinea come il tema della sicurezza all\u2019interno del carcere sia oggi \u201cfortemente compromesso\u201d, con ricadute pesanti su medici, infermieri, agenti della Polizia Penitenziaria, operatori e detenuti pi\u00f9 fragili.<\/p>\n<h3>Timori per l\u2019assistenza sanitaria ai detenuti<\/h3>\n<p>Nelle ultime ore il Garante ha tentato, senza successo, di mettersi in contatto con il coordinatore sanitario dell\u2019istituto, il dottor Nicola Pangallo, per comprendere l\u2019entit\u00e0 dei danni e le conseguenze sull\u2019assistenza sanitaria: \u201ctemo che la distruzione degli impianti dedicati alla telemedicina possa determinare un grave pregiudizio all\u2019assistenza sanitaria delle persone detenute\u201d, afferma Russo, annunciando la richiesta urgente di un chiarimento istituzionale nelle sedi competenti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-293569\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/garante-russo-telemedicina.jpg\" alt=\"garante russo telemedicina\" width=\"564\" height=\"349\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/garante-russo-telemedicina.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/garante-russo-telemedicina-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/garante-russo-telemedicina-768x475.jpg 768w\" sizes=\"auto, (max-width: 564px) 100vw, 564px\" \/><\/p>\n<p>Nel suo intervento il Garante richiama l\u2019attenzione sulle difficolt\u00e0 storiche del carcere di Arghill\u00e0, caratterizzato da <strong>problemi strutturali, isolamento territoriale e dalla presenza di detenuti con elevata complessit\u00e0 sanitaria e comportamentale. <\/strong>Accanto alla gestione delle patologie psichiatriche, Russo evidenzia anche il problema di detenuti con disturbi della personalit\u00e0 e condotte aggressive, per i quali ritiene indispensabile \u201cuna riflessione attenta, seria, scientifica e multidisciplinare. Non \u00e8 pi\u00f9 accettabile che il sistema della sanit\u00e0 penitenziaria calabrese continui a essere trattato come una sanit\u00e0 di serie B\u201d.<\/p>\n<h3>\u201cDistruggere la telemedicina significa colpire la dignit\u00e0 umana\u201d<\/h3>\n<p>\u201cLa telemedicina, in un territorio complesso come quello calabrese e in istituti difficili come Arghill\u00e0, rappresenta uno strumento essenziale di civilt\u00e0 giuridica, sicurezza sanitaria e tutela dei diritti fondamentali. Distruggere quei presidi &#8211; prosegue Russo &#8211; significa colpire non soltanto l\u2019organizzazione sanitaria, ma anche il principio costituzionale secondo cui ogni persona, anche se detenuta, conserva intatto il diritto alla salute, alla cura e alla dignit\u00e0 umana\u201d.<\/p>\n<p>Il Garante invoca un <strong>immediato intervento coordinato delle istituzioni<\/strong> chiedendo investimenti strutturali, rafforzamento del personale, maggiore integrazione tra amministrazione penitenziaria e sistema sanitario regionale, oltre a protocolli di sicurezza adeguati: \u201c<strong>continuare a sottovalutare ci\u00f2 che accade negli istituti penitenziari ad alta complessit\u00e0 significa mettere a rischio lo Stato stesso<\/strong>, la sicurezza collettiva e la credibilit\u00e0 delle istituzioni\u201d, conclude Russo.\u00a0Infine, il Garante ha espresso <strong>solidariet\u00e0 ai medici<\/strong>, agli infermieri, agli agenti della Polizia Penitenziaria e a tutto il personale del carcere di Arghill\u00e0 \u201cche continuano a operare in un contesto difficile e rischioso, garantendo ogni giorno la tenuta di un presidio essenziale dello Stato\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Duro intervento del Garante regionale Russo dopo il grave evento critico nella Casa Circondariale di Arghill\u00e0. Danneggiate le apparecchiature sanitarie dedicate alla telemedicina \u201ccolpito un presidio essenziale di civilt\u00e0 e tutela della salute\u201d<\/p>\n","protected":false},"author":42,"featured_media":238068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-293568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/293568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=293568"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/293568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/238068"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=293568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=293568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=293568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}