{"id":293716,"date":"2026-05-26T16:02:19","date_gmt":"2026-05-26T14:02:19","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=293716"},"modified":"2026-05-27T12:32:19","modified_gmt":"2026-05-27T10:32:19","slug":"agrintesa-calabria-castrovillari-nettarine","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/agrintesa-calabria-castrovillari-nettarine\/","title":{"rendered":"Agrintesa scommette sulla Calabria: da Castrovillari parte la rivoluzione delle nettarine piatte"},"content":{"rendered":"<p><em>Servizio di Francesca Achito, riprese e montaggio Vincenzo Provenzano<\/em><\/p>\n<p>COSENZA &#8211; Una strategia di sviluppo che mette al centro il territorio calabrese, puntando su <b>investimenti mirati, sinergie di filiera e il rispetto dei valori di legalit\u00e0<\/b>. \u00c8 questo il fulcro dei nuovi progetti presentati da <a href=\"https:\/\/www.agrintesa.it\/\" target=\"_blank\" rel=\"noopener\"><b data-path-to-node=\"2\" data-index-in-node=\"214\">Agrintesa<\/b><\/a>, realt\u00e0 cooperativa di primo piano che conta 3.500 associati, 2.300 collaboratori e che ha chiuso l&#8217;ultimo bilancio (al 30 aprile 2026) con un valore della produzione di 450 milioni di euro.<\/p>\n<p data-path-to-node=\"3\">Il legame con la regione, fondamentale per la crescita del comparto ortofrutticolo del Gruppo, si \u00e8 consolidato in modo decisivo a partire dal 1\u00b0 giugno 2024 con l&#8217;unione strategica per incorporazione della cooperativa OSAS.<\/p>\n<p>Questo percorso di consolidamento \u00e8 stato condiviso e approfondito a Castrovillari durante l&#8217;incontro <b data-path-to-node=\"4\" data-index-in-node=\"102\">\u201cRadici di Futuro. Progetti, investimenti e sviluppo per una frutticoltura innovativa\u201d<\/b>. L&#8217;appuntamento, organizzato da Agrintesa e Gruppo Alegra, ha visto la partecipazione attiva di agricoltori, rappresentanti istituzionali, partner della GDO e organi di stampa per fare il punto sui prossimi passi del settore.<\/p>\n<p data-path-to-node=\"4\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-293723 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/nettarine-castrovillari-3-1024x768.png\" alt=\"nettarine-castrovillari-3\" width=\"548\" height=\"411\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/nettarine-castrovillari-3-1024x768.png 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/nettarine-castrovillari-3-300x225.png 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/nettarine-castrovillari-3-768x576.png 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/nettarine-castrovillari-3.png 1183w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><\/p>\n<h2>I numeri di Agrintesa: il peso della cooperativa e la forza del comparto calabrese<\/h2>\n<p data-path-to-node=\"2\">I numeri complessivi di <b data-path-to-node=\"2\" data-index-in-node=\"24\">Agrintesa<\/b> testimoniano la portata della cooperativa, che pu\u00f2 contare su una superficie coltivata imponente: <b data-path-to-node=\"2\" data-index-in-node=\"132\">10.500 ettari di frutteti, 7.000 ettari di vigneti e 600 ettari dedicati alle colture orticole<\/b>.\u00a0All&#8217;interno di questo scacchiere, la <b data-path-to-node=\"3\" data-index-in-node=\"37\">Calabria<\/b> gioca un ruolo strategico fondamentale, guidata da <b data-path-to-node=\"3\" data-index-in-node=\"97\">173 produttori associati<\/b> e sostenuta dal lavoro di <b data-path-to-node=\"3\" data-index-in-node=\"148\">151 dipendenti<\/b> impiegati nel polo di Castrovillari.\u00a0Le attivit\u00e0 sul territorio regionale si concentrano principalmente in due grandi bacini produttivi: l&#8217;area di <b data-path-to-node=\"4\" data-index-in-node=\"110\">Cosenza\/Castrovillari<\/b> e quella di <b data-path-to-node=\"4\" data-index-in-node=\"144\">Reggio Calabria\/Gioia Tauro\/Rosarno<\/b>.<\/p>\n<h3 data-path-to-node=\"6\">La mappa delle colture in Calabria<\/h3>\n<p data-path-to-node=\"7\">La produzione calabrese investe complessivamente su <b data-path-to-node=\"7\" data-index-in-node=\"52\">1.282 ettari<\/b>, focalizzandosi su coltivazioni d&#8217;eccellenza e ad alta redditivit\u00e0:<\/p>\n<ul data-path-to-node=\"8\">\n<li>\n<p data-path-to-node=\"8,0,0\"><b data-path-to-node=\"8,0,0\" data-index-in-node=\"0\">Kiwi:<\/b> 647 ettari (la coltura principale della regione)<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,1,0\"><b data-path-to-node=\"8,1,0\" data-index-in-node=\"0\">Drupacee:<\/b> 442 ettari (suddivisi tra pesche, nettarine e le apprezzate variet\u00e0 piatte).<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,2,0\"><b data-path-to-node=\"8,2,0\" data-index-in-node=\"0\">Agrumi:<\/b> 92 ettari.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"8,3,0\"><b data-path-to-node=\"8,3,0\" data-index-in-node=\"0\">Altre variet\u00e0:<\/b> la parte restante del territorio \u00e8 riservata a produzioni minori.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-293722 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Immagine-2026-05-26-155904-1024x538.png\" alt=\"nettarine\" width=\"630\" height=\"331\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Immagine-2026-05-26-155904-1024x538.png 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Immagine-2026-05-26-155904-300x158.png 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Immagine-2026-05-26-155904-768x403.png 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Immagine-2026-05-26-155904.png 1247w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<\/li>\n<\/ul>\n<h3>Il progetto sulle nettarine in Calabria<\/h3>\n<p>&#8220;\u00c8 un momento bello perch\u00e9 due anni fa, abbiamo fatto una<strong> fusione fra la cooperativa Osas e la cooperativa Agrintesa.<\/strong> Oggi, a distanza di due anni, presentiamo un nuovo progetto che riguarda sempre il nostro tema che \u00e8 la frutticoltura. Stiamo sviluppando un progetto di nettarine piatte che verranno lavorate qui nel territorio di Castrovillari, in questa zona qui. Lo dichiara <strong>Luigi Nola Consigliere Agrintesa.<\/strong><\/p>\n<p>&#8220;Quindi proponiamo questo nuovo progetto di fronte ai sindacati, di fronte al territorio, per dimostrare che questa cooperativa non solo si \u00e8 rinnovata, ma ha ambizioni maggiori rispetto a quelle che aveva prima. Quindi fa tutto parte di un percorso che abbiamo pensato negli anni passati e che oggi portiamo a compimento.&#8221;<\/p>\n<p><strong>L&#8217;assessore regionale all&#8217;agricolutura Gianluca Gallo<\/strong> parla di &#8220;un settore, quello delle drupacee, nel quale ormai<strong> la Calabria ha un ruolo di leadership assoluto, pesche e <a href=\"https:\/\/quicosenza.it\/news\/passione-mediterranea-aop-in-calabria-nasce-la-prima-rete-tra-produttori-ortofrutticoli\/\" target=\"_blank\" rel=\"noopener\">nettarine<\/a><\/strong>. In questa nuova definizione, in questa nuova variet\u00e0, quella delle Ondine, credo che sia un esperimento innovativo che vede un&#8217;ottima congiuntura fra aziende del Mezzogiorno che hanno una grande capacit\u00e0 cooperativa e una grossa impresa come Agrintesa che investe in Calabria per aumentare anche il ritorno in termini di produzione e in termini di giornate lavorative&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I vertici di Agrintesa presentano a Castrovillari un piano di crescita per i 1.282 ettari calabresi: impianti tecnologici, export e alleanze internazionali con Spagna e Francia per far crescere l&#8217;ortofrutta locale nel segno della trasparenza. Investimenti sulle nettarine piatte e non solo<\/p>\n","protected":false},"author":58,"featured_media":293721,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-293716","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-provincia","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/293716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=293716"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/293716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/293721"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=293716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=293716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=293716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}