{"id":29387,"date":"2014-01-13T19:07:50","date_gmt":"2014-01-13T18:07:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-punto-sulla-diciannovesima-giornata-di-lega-pro-2-gir-b\/"},"modified":"2023-01-17T12:45:54","modified_gmt":"2023-01-17T11:45:54","slug":"12295-il-punto-sulla-diciannovesima-giornata-di-lega-pro-2-gir-b","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12295-il-punto-sulla-diciannovesima-giornata-di-lega-pro-2-gir-b\/","title":{"rendered":"Il punto sulla diciannovesima giornata di Lega pro 2 gir. B"},"content":{"rendered":"<p>COSENZA &nbsp;&#8211; Equilibrio, questa \u00e8 la parola d&#8217;ordine dell&#8217;inizio del girone di ritorno.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Anche le squadre che sono riuscite a vincere, lo hanno fatto con grosse difficolt\u00e0. Ben cinque sono stati i pareggi e quattro le vittorie, con l&#8217;unica affermazione in trasferta fatta registrare <strong>dall&#8217;Ischia<\/strong> sul campo del <strong>Gavorrano<\/strong>. Il segno x caratterizza gli incroci fra le prime quattro squadre del campionato, &nbsp;dimostrando come il livello tecnico e tattico di <strong>Teramo<\/strong>, <strong>Cosenza<\/strong>, <strong>Foggia<\/strong> e <strong>Casertana<\/strong> sia praticamente uguale. Se in <strong>Foggia<\/strong>&#8211;<strong>Teramo<\/strong> il risultato di 1-1 \u00e8 scaturito da una gara abbastanza lineare, il 2-2 di <strong>Cosenza<\/strong>&#8211;<strong>Casertana<\/strong> \u00e8 risultato che, ad un certo punto della partita, non sembrava pi\u00f9 possibile che potesse verificarsi. Alla fine del primo tempo, la squadra di <strong>Cappellacci<\/strong> era sotto di due goal,(frutto di disattenzioni) ma che nel secondo tempo \u00e8 riuscita nell&#8217;impresa di recuperare. Cuore e grinta hanno permesso ai lupi di non perdere e mantenere l&#8217;imbattibilit\u00e0 del San Vito. Tre punti pesanti li conquista l&#8217;Ischia, battendo a domicilio un <strong>Gavorrano<\/strong> in caduta libera. Vittoria importante del <strong>Martina<\/strong>, che con l&#8217;arrivo di <strong>Tommaso<\/strong> <strong>Napoli<\/strong> in panchina, guadagna tre punti di vitale importanza per la lotta salvezza. Vince il <strong>Messina<\/strong> di <strong>Lo<\/strong> <strong>Monaco<\/strong>, che, con il minimo scarto infligge al <strong>Tuttocuio<\/strong> l&#8217;ennesima sconfitta. Punti importanti anche per il <strong>Sorrento<\/strong>, che si aggiudica la partita contro un <strong>Aprilia<\/strong> lontana parente della squadra di inizio campionato. Per il resto tutti pareggi, che mantengono inalterate le posizioni in classifica di <strong>Aversa<\/strong>, <strong>Melfi<\/strong>, <strong>Chieti<\/strong>, <strong>Vigor<\/strong> <strong>Lamezia<\/strong>, <strong>Poggibonsi<\/strong> e <strong>Arzanese<\/strong>. Probabilmente nel girone di ritorno, di queste domeniche ne vedremo tante, con squadre che tenteranno in tutti i modi di arrivare ai traguardi prefissati. Sicuramente il calcio mercato cambier\u00e0 i valori in campo, con squadre che saranno <strong>ritoccate<\/strong>, ma non sappiamo se <strong>migliorate<\/strong>. Sognare non \u00e9 vietato a nessuno, ma non a tutti riuscir\u00e0 l&#8217;impresa di arrivare al traguardo della <strong>salvezza<\/strong> o della <strong>Lega<\/strong> <strong>pro<\/strong> <strong>unica<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &nbsp;&#8211; Equilibrio, questa \u00e8 la parola d&#8217;ordine dell&#8217;inizio del girone di ritorno.<\/p>\n","protected":false},"author":22,"featured_media":29388,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-29387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29387"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29388"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}