{"id":29397,"date":"2014-01-14T07:52:46","date_gmt":"2014-01-14T06:52:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/a-bisignano-festosa-celebrazione-del-battesimo-di-gesu\/"},"modified":"2023-01-17T12:45:55","modified_gmt":"2023-01-17T11:45:55","slug":"12300-a-bisignano-festosa-celebrazione-del-battesimo-di-gesu","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12300-a-bisignano-festosa-celebrazione-del-battesimo-di-gesu\/","title":{"rendered":"A Bisignano festosa celebrazione del Battesimo di Ges\u00f9"},"content":{"rendered":"<p>BISIGNANO (CS) &#8211; Celebrata in maniera festosa e ricca di segni la festivit\u00e0 dedicata al Battesimo di Ges\u00f9.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Nelle due parrocchie del centro citt\u00e0, quella di Santa Croce e Santa Maria Assunta, il parroco, don Maurizio Spadafora insieme ai catechisti, ha pensato di dedicare particolare attenzione a questa importante ricorrenza che la chiesa ricorda a met\u00e0 gennaio. Cos\u00ec, sull\u2019altare \u201cfestosa\u201d, c\u2019erano anche i bambini che devono fare a giugno la prima comunione che, fra le altre cose, hanno ricevuto la candela, segno della luce anche perch\u00e9 il Battesimo di Ges\u00f9 \u00e8 ricordato come il primo dei misteri della luce di cui \u00e8 composto il rosario. I ragazzi, accompagnati dai genitori, hanno apprezzato l\u2019iniziativa del parroco e dei catechisti. La festa continuer\u00e0 di domenica in domenica, con un programma specifico gi\u00e0 concordato, che vedr\u00e0 la partecipazione attiva dei ragazzi e delle loro famiglie. Intanto, dopo il successo del presepe vivente, i giovani del quartiere si preparano per l\u2019organizzazione della Passione.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BISIGNANO (CS) &#8211; Celebrata in maniera festosa e ricca di segni la festivit\u00e0 dedicata al Battesimo di Ges\u00f9.<\/p>\n","protected":false},"author":22,"featured_media":29398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-29397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29397"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29398"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}