{"id":29399,"date":"2014-01-14T08:44:43","date_gmt":"2014-01-14T07:44:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/bisignano-anche-i-santi-hanno-bisogno-di-protezione\/"},"modified":"2023-01-17T12:45:55","modified_gmt":"2023-01-17T11:45:55","slug":"12301-bisignano-anche-i-santi-hanno-bisogno-di-protezione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12301-bisignano-anche-i-santi-hanno-bisogno-di-protezione\/","title":{"rendered":"Bisignano, &#8220;anche i Santi hanno bisogno di protezione&#8221;"},"content":{"rendered":"<p>BISIGNANO (CS) &#8211; Per iniziativa del sindaco della citt\u00e0, Umile Bisignano e della sua amministrazione, la statua di San Pio, posta al centro della piazza di San Simone, da ieri \u00e8 protetta da una struttura in acciaio.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La struttura \u00e8 stata realizzata e donata, a titolo di devozione, dal titolare della Alimec, lavorazioni in acciaio, Rosario Migliuri che, insieme al fratello Luciano, consigliere comunale di maggioranza, hanno voluto fare questo dono alla citt\u00e0. Ora, ha detto il sindaco, sar\u00e0 cura del comune illuminare la statua dedicata al Santo di Pietralcina per dargli il giusto rilievo, venendo incontro anche alle esigenze sollevate dal gruppo di San Pio, molto numeroso e devoto. E\u2019 stato infatti il gruppo di preghiera \u201cPadre Pio\u201d che, ha voluto la realizzazione della statua, oltre un decennio addietro, attorno alla quale si radunano in preghiera. Presenti al montaggio della struttura oltre al sindaco anche l\u2019assessore all\u2019urbanistica, Mario Umile D\u2019Alessandro il quale, insieme al Primo Cittadino, ha annunciato l\u2019intitolazione di quel lembo di terra, attrezzato anche a parco giochi per i bambini, a San Pio. Dopo il montaggio della struttura, il lavoro \u00e8 stato benedetto da Padre Antonio Martella, padre Guardiano del convento di Sant\u2019Umile. Questo anche a dimostrazione, se si vuole una nota di colore, che non c\u2019\u00e8 \u201cgelosia\u201d fra i Santi e che il concittadino Sant\u2019Umile \u00e8 e rimane, saldamente, nei cuori dei bisignanesi che, nelle loro preghiere, vogliono affidarsi anche al Santo di Pietralcina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BISIGNANO (CS) &#8211; Per iniziativa del sindaco della citt\u00e0, Umile Bisignano e della sua amministrazione, la statua di San Pio, posta al centro della piazza di San Simone, da ieri \u00e8 protetta da una struttura in acciaio.<\/p>\n","protected":false},"author":22,"featured_media":29400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-29399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29399"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29400"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}