{"id":293992,"date":"2026-05-29T08:42:56","date_gmt":"2026-05-29T06:42:56","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=293992"},"modified":"2026-05-29T08:42:56","modified_gmt":"2026-05-29T06:42:56","slug":"caldo-calabria-fillea-cgil-ordinanza-lavoratori","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/caldo-calabria-fillea-cgil-ordinanza-lavoratori\/","title":{"rendered":"Caldo e stress termico, Fillea Cgil Calabria: \u00absubito l\u2019ordinanza a tutela dei lavoratori fino al 30 settembre\u00bb"},"content":{"rendered":"<p>CATANZARO \u2013 Con l\u2019avvicinarsi della stagione estiva, del caldo, e del previsto aumento delle temperature, la Fillea Cgil Calabria torna a chiedere con forza alla Regione <strong>l\u2019emanazione immediata<\/strong> <strong>dell\u2019ordinanza \u201c<a href=\"https:\/\/quicosenza.it\/news\/caldo-in-calabria-azioni-di-contrasto-tutela-lavoratori-pronti-soccorso-potenziati-e-piano-antincendio\/\">Anti-Caldo<\/a>\u201d<\/strong> per tutelare la salute e la sicurezza dei <strong>lavoratori esposti al rischio termico.<\/strong><\/p>\n<p>Il sindacato lancia un appello diretto al presidente della Regione Calabria, Roberto Occhiuto, affinch\u00e9 <strong>vengano definite in tempi rapidi le linee guida e i provvedimenti necessari per affrontare le ondate di calore<\/strong> che, soprattutto nelle aree interne della Calabria, superano stabilmente i 35 gradi.<\/p>\n<h3>Caldo in Calabria: \u201cnon possiamo aspettare l\u2019emergenza\u201d<\/h3>\n<p>Secondo la <a href=\"https:\/\/www.filleacgil.net\/calabria.html\" rel=\"noopener\">Fillea Cgil Calabria<\/a>, e il segretario Simone Celebre, i cambiamenti climatici hanno ormai trasformato il caldo estremo in un fenomeno strutturale e non pi\u00f9 straordinario. Da qui la necessit\u00e0 di superare la logica emergenziale che negli anni scorsi ha portato all\u2019adozione tardiva delle ordinanze di tutela.<\/p>\n<p>\u201cL\u2019emissione dell\u2019ordinanza, ottenuta grazie alla nostra mobilitazione, negli anni scorsi ha sicuramente salvato delle vite. Ma non possiamo rincorrere il termometro ogni anno. Chiediamo al Presidente Occhiuto un atto di responsabilit\u00e0: l&#8217;ordinanza deve essere emanata subito per proteggere i lavoratori fin dalle prime ondate di calore\u201d, dichiara Simone Celebre, segretario generale della Fillea Cgil Calabria.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-293993\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Fillea-Cgil-Simone-Celebre.jpg\" alt=\"Fillea Cgil Simone Celebre - caldo\" width=\"606\" height=\"375\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Fillea-Cgil-Simone-Celebre.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Fillea-Cgil-Simone-Celebre-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Fillea-Cgil-Simone-Celebre-768x475.jpg 768w\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" \/><\/p>\n<p>Tra le principali misure richieste dal sindacato c\u2019\u00e8 la <strong>sospensione delle attivit\u00e0 dalle 12:30 alle 16 nei cantieri edili civili e stradali,<\/strong> <strong>nelle cave e nei settori affini nei giorni in cui il sito Workclimate segnali un livello di rischio \u201calto\u201d<\/strong>.<\/p>\n<p>La Fillea Cgil chiede inoltre:<\/p>\n<p>&#8211; lo stop automatico ai lavori e accesso alla Cassa Integrazione Guadagni Ordinaria in caso di temperature pari o superiori ai 35 gradi;<br \/>\n&#8211; l&#8217;estensione delle tutele anche ai lavoratori impiegati in ambienti chiusi privi di adeguata ventilazione;<br \/>\n&#8211; l&#8217;obbligo per le imprese di garantire acqua potabile e aree ombreggiate per le pause;<br \/>\n&#8211; la rimodulazione degli orari di lavoro privilegiando le prime ore del mattino o i turni serali;<br \/>\n&#8211; il riconoscimento dei ritardi nei lavori causati dalle interruzioni climatiche;<br \/>\n&#8211; la proroga della validit\u00e0 dell\u2019ordinanza fino al 30 settembre.<\/p>\n<p>Il sindacato chiede anche controlli rigorosi da parte degli Ispettorati Territoriali del Lavoro per evitare violazioni o applicazioni distorte delle eventuali misure:\u00a0\u201cchiediamo inoltre agli <strong>Ispettorati Territoriali del Lavoro controlli stringenti<\/strong> su tutto il territorio per evitarne usi distorti. La salute e la vita di chi lavora &#8211; conclude Simone Celebre &#8211; non possono essere subordinate a ritardi burocratici. La sicurezza \u00e8 un bene supremo dell&#8217;intera comunit\u00e0\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;appello al presidente Roberto Occhiuto per misure urgenti a tutela dei lavoratori esposti alle alte temperature. La richiesta: stop ai cantieri nelle ore pi\u00f9 calde e ordinanza valida fino al 30 settembre<\/p>\n","protected":false},"author":42,"featured_media":261178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-293992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/293992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=293992"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/293992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/261178"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=293992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=293992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=293992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}