{"id":29459,"date":"2014-01-16T08:53:17","date_gmt":"2014-01-16T07:53:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/arrestato-boss-della-cosca-gallace-gallelli-latitante-da-luglio\/"},"modified":"2023-01-17T12:45:57","modified_gmt":"2023-01-17T11:45:57","slug":"12331-arrestato-boss-della-cosca-gallace-gallelli-latitante-da-luglio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12331-arrestato-boss-della-cosca-gallace-gallelli-latitante-da-luglio\/","title":{"rendered":"Arrestato boss  della cosca Gallace-Gallelli, latitante da Luglio"},"content":{"rendered":"<p>CATANZARO &#8211; E\u2019 stato bloccato dai carabinieri mentre era in compagnia della fidanzata ventunenne Cosimo Damiano Gallace, di 24 anni, figlio di Vincenzo, boss della cosca Gallace-Gallelli operante tra Badolato e Guardavalle.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Arrestata la corsa, arrestato, soprattutto, il protagonista della fuga ritenuto \u201c elemento di spicco\u201d del clan: il successo dell\u2019operazione va attribuito ai carabinieri del reparto operativo del Comando provinciale di Catanzaro. Il giovane era ricercato dallo scorso luglio quando sfugg\u00ec all&#8217;operazione Itaca. Gallace \u00e8 stato individuato in una casa a Guardavalle e la sua compagna \u00e8 stata arrestata per favoreggiamento. era armato e non ha opposto resistenza. L\u2019operazione Itaca ha avviato e ottenuto l\u2019 arresto di 25 persone ritenute capi e gregari della cosca Gallace-Gallelli, operante nel basso Ionio catanzarese, ma con ramificazioni nella zona di Nettuno, nel Lazio e nel milanese. Nell&#8217;ambito della stessa inchiesta \u00e8 stato, inoltre, indagato il sindaco di Badolato Giuseppe Nicola Parretta ed \u00e8 stato arrestato un imprenditore del settore nautico, Antonio Ranieri. Secondo la Dda di Catanzaro, che ha coordinato l&#8217;inchiesta, il gruppo dei Gallace-Gallelli ha una &#8221;elevata capacita&#8217; criminale&#8221; ed \u00e8 attivo nelle estorsioni, anche ai danni dell&#8217;impresa che ha realizzato il porto di Badolato, nel traffico di droga e nell&#8217;usura. Fine della latitanza, dunque, per l\u2019arrestato che dovr\u00e0 rispondere dell\u2019accusa di associazione mafiosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; E\u2019 stato bloccato dai carabinieri mentre era in compagnia della fidanzata ventunenne Cosimo Damiano Gallace, di 24 anni, figlio di Vincenzo, boss della cosca Gallace-Gallelli operante tra Badolato e Guardavalle.<\/p>\n","protected":false},"author":22,"featured_media":29460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-29459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29459"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29460"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}