{"id":295433,"date":"2026-06-15T12:15:10","date_gmt":"2026-06-15T10:15:10","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=295433"},"modified":"2026-06-15T17:14:35","modified_gmt":"2026-06-15T15:14:35","slug":"cosenza-calcio-bivio-nodo-iscrizione-cessione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-calcio-bivio-nodo-iscrizione-cessione\/","title":{"rendered":"Cosenza Calcio ad un bivio: ore decisive tra il nodo iscrizione e il giallo societario"},"content":{"rendered":"<p>COSENZA &#8211; Le prossime quarantotto ore saranno cruciali (non che le precedenti non lo fossero) per il <strong>futuro del Cosenza Calcio<\/strong>, ma guai a illudersi, anzi. Il popolo rossobl\u00f9 vive un <strong>momento di profonda incertezza<\/strong>, sospesa tra scadenze burocratiche imminenti del club del patron <strong>Eugenio Guarascio<\/strong> e le voci sempre pi\u00f9 insistenti su un possibile e allo stesso tempo complicato cambio di propriet\u00e0.<\/p>\n<p>E proprio sulla questione societaria, nelle ultime ore \u00e8 arrivata una netta presa di posizione che contribuisce a fare chiarezza sulla cordata di imprenditori interessata al club rossobl\u00f9. I<strong> soci di maggioranza del gruppo<\/strong> hanno precisato che non si tratta di un&#8217;azione collettiva, bens\u00ec di una scelta personale di <strong>Vincenzo Rota<\/strong>.<\/p>\n<p>L&#8217;azienda con sede a Spezzano Piccolo, di fatto, non sarebbe coinvolta nella &#8220;<em>complicata trattativa<\/em>&#8221; dall&#8217;<strong>esito incerto<\/strong> (a meno di clamorose <strong>novit\u00e0<\/strong> dell&#8217;ultimo minuto che, per\u00f2, si affievoliscono visti i tempi ristretti e le tante altre problematiche).<\/p>\n<h2>Cosenza Calcio fra cessione (molto complicata) e le precisazioni che fanno pensare<\/h2>\n<p>Ad intervenire ufficialmente sono stati <strong>Stefania<\/strong>, <strong>Concettina e Umberto Rota<\/strong>, fratelli di Vincenzo Rota e soci di maggioranza dell&#8217;azienda presilana &#8220;<strong>San Vincenzo di Fernando Rota Srl<\/strong>&#8220;. Attraverso una nota ufficiale, infatti, i soci hanno voluto smentire categoricamente il coinvolgimento diretto dell&#8217;azienda nella presunta trattativa per la <strong>possibile acquisizione<\/strong> del Cosenza Calcio, dichiarando di aver appreso la notizia esclusivamente dagli organi di stampa.<\/p>\n<p>&#8220;<strong><em>Nessun organo societario competente ha mai autorizzato, deliberato o approvato l&#8217;avvio di una trattativa di tale natura<\/em><\/strong>&#8220;, si legge nella nota. I firmatari hanno poi precisato che &#8220;<em>nessun amministratore o dirigente possiede deleghe per rappresentare l&#8217;azienda in questa operazione. <strong>Di conseguenza, qualsiasi proposta o manifestazione d&#8217;interesse \u00e8 da considerarsi esclusivamente a titolo personale e sotto la responsabilit\u00e0 di chi la promuove<\/strong>. La nota si chiude con una formale presa di distanza e la riserva di tutelare l&#8217;immagine della societ\u00e0 nelle sedi opportune<\/em>&#8220;, continua la nota.<\/p>\n<h3>Iniziativa personale, a breve dentro o fuori<\/h3>\n<p>Il coinvolgimento dell&#8217;azienda non \u00e8 mai stato messo in bella mostra, anzi. Si \u00e8 parlato dell&#8217;iniziativa personale di Vincenzo Rota, mossosi autonomamente insieme ad altri imprenditori locali ed esteri tramite la ormai nota <strong>PEC formale<\/strong>. La precisazione dei soci di maggioranza della &#8220;San Vincenzo&#8221; resta comunque un atto legittimo per<strong> tutelare il marchio di famiglia<\/strong>. La giornata di oggi dir\u00e0 molto di pi\u00f9 su questa trattativa: si \u00e8 ormai al <strong>&#8220;dentro o fuori&#8221; definitivo<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-285405 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Stadio-Marulla-Cuva-Nord-traffico-300x187.jpg\" alt=\"Stadio-Marulla-Curva-Nord-traffico chiusura viale MAgna grecia viabilit\u00e0\" width=\"540\" height=\"337\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Stadio-Marulla-Cuva-Nord-traffico-300x187.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Stadio-Marulla-Cuva-Nord-traffico-768x479.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/02\/Stadio-Marulla-Cuva-Nord-traffico.jpg 970w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/p>\n<h4>L&#8217;incognita stadio &#8220;Marulla&#8221;<\/h4>\n<p>Parallelamente alle vicende societarie, c&#8217;\u00e8 da risolvere il<strong> rebus iscrizione <a href=\"https:\/\/quicosenza.it\/news\/cosenza-calcio-stadio-marulla-iscrizione\/\" target=\"_blank\" rel=\"noopener\">al prossimo campionato<\/a><\/strong>. Il passaggio burocratico imprescindibile \u00e8 l&#8217;indicazione di un impianto sportivo idoneo per le gare casalinghe. Al momento, tuttavia, lo stadio &#8220;San Vito-Gigi Marulla&#8221; non pu\u00f2 essere indicato nella documentazione. Un ostacolo non da poco che la dirigenza <strong><a href=\"https:\/\/www.ilcosenza.it\/\" target=\"_blank\" rel=\"noopener\">dovr\u00e0 superare nelle prossime ore<\/a><\/strong>. Gli interrogativi restano molti, il tempo stringe: il popolo rossobl\u00f9 attende risposte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La maggioranza dell&#8217;azienda guidata da Vincenzo Rota fa alcune precisazioni in merito all&#8217;azione personale dell&#8217;imprenditore, precisando alcuni aspetti gi\u00e0 comunque emersi. Nel frattempo le prossime ore saranno decisive per l&#8217;iscrizione del Cosenza Calcio: intanto continua la telenovela sulla presunta cessione <\/p>\n","protected":false},"author":93,"featured_media":241738,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-295433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/295433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/93"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=295433"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/295433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/241738"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=295433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=295433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=295433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}