{"id":295434,"date":"2026-06-15T11:52:36","date_gmt":"2026-06-15T09:52:36","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=295434"},"modified":"2026-06-15T15:55:36","modified_gmt":"2026-06-15T13:55:36","slug":"tragedia-sfiorata-ponte-celico-mamma-salvata-pa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/tragedia-sfiorata-ponte-celico-mamma-salvata-pa\/","title":{"rendered":"Tragedia sfiorata sul ponte di Celico: mamma cosentina di 29 anni salvata da un passante"},"content":{"rendered":"<p>CELICO (CS) &#8211; Empatia e prontezza hanno permesso di scongiurare il peggio, ieri sera, intorno alle ore 22.00 sul <strong>ponte di Celico<\/strong>. Qui una <strong>mamma cosentina di 29 anni<\/strong> stava per compiere un gesto estremo ma \u00e8 stata <strong>salvata grazie all&#8217;intervento di alcuni passanti. Sul posto sono anche arrivati i carabinieri<\/strong> e i <strong>sanitari del 118 di Cosenza<\/strong> che hanno poi portato la giovane in ospedale all&#8217;Annunziata.<\/p>\n<p>La ragazza, che avrebbe anche una bimba di un anno, secondo quanto ricostruito, avrebbe accostato e lasciato la propria auto nei pressi del bivio di Celico per poi dirigersi, a piedi, verso il viadotto Cannavino. A notare la scena e a evitare il peggio \u00e8 stato un <strong>automobilista di passaggio <\/strong>che non ha esitato a fermarsi e a intervenire immediatamente tentando di parlare con lei.<\/p>\n<h3>Ponte di Celico, mamma salvata e messa in sicurezza<\/h3>\n<p>L&#8217;uomo \u00e8 rimasto con la 29enne fino all&#8217;arrivo dei carabinieri. <strong>&#8220;Le ho parlato, l&#8217;ho fatta sfogare&#8221;<\/strong><a href=\"http:\/\/facebook.com\/story.php?story_fbid=10244254774171470&amp;id=1441459473&amp;rdid=ZupJHfvA3jxdGrIO&amp;share_url=https%3A%2F%2Fwww.facebook.com%2Fshare%2Fp%2F1R2aPM4nwY%2F#\" target=\"_blank\" rel=\"noopener\"> racconta sui social l&#8217;uomo<\/a> che insieme ai colleghi \u00e8 riuscito a farla desistere dal gesto e a metterla in sicurezza. Sul posto sono giunti anche i sanitari di &#8220;Amicizia e Solidariet\u00e0 Presilana&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La giovane aveva accostato e lasciato la propria auto nei pressi del bivio di Celico per poi dirigersi, a piedi, verso il viadotto. Fondamentale il passaggio di un automobilista <\/p>\n","protected":false},"author":90,"featured_media":149357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-295434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/295434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=295434"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/295434\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/149357"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=295434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=295434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=295434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}